{"id":4117,"date":"2025-02-03T09:46:22","date_gmt":"2025-02-03T08:46:22","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/?p=4117"},"modified":"2025-02-03T09:46:22","modified_gmt":"2025-02-03T08:46:22","slug":"aprendizaje-por-capacitacion","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/2025\/02\/03\/aprendizaje-por-capacitacion\/","title":{"rendered":"Aprendizaje por capacitaci\u00f3n"},"content":{"rendered":"<p>En esta ocasi\u00f3n, les ha tocado a la mitad de quinto A experimentar, trabajar y colaborar en el huerto escolar. Como ya os hemos dicho otras veces, es un momento muy especial para ellos y ellas, ya que tienen la posibilidad de salir al aire libre e investigar los contenidos que se dan en el aula.<\/p>\n<ul>\n<li><a href=\"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/galeria-de-fotos\/\" target=\"_blank\" rel=\"noopener\">Enlace a la galer\u00eda.<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>En esta ocasi\u00f3n, les ha tocado a la mitad de quinto A experimentar, trabajar y colaborar en el huerto escolar. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4118,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"post_folder":[],"class_list":["post-4117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quinto-de-primaria"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto.jpg",850,425,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto.jpg",850,425,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto.jpg",850,425,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto-300x150.jpg",300,150,true],"large":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto.jpg",850,425,false],"thumblist":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto-500x425.jpg",500,425,true],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto.jpg",850,425,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto.jpg",850,425,false],"sydney-large-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto.jpg",850,425,false],"sydney-medium-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto-550x400.jpg",550,400,true],"sydney-small-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto-230x115.jpg",230,115,true],"sydney-service-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto-350x175.jpg",350,175,true],"sydney-mas-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto-480x240.jpg",480,240,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto.jpg",360,180,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto.jpg",360,180,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2025\/02\/huerto.jpg",850,425,false]},"rttpg_author":{"display_name":"cp.navalazarza.sanagustin","author_link":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/author\/cuenta_cp-navalazarza-sanagustin\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/category\/quinto-de-primaria\/\" rel=\"category tag\">5\u00ba de Primaria<\/a>","rttpg_excerpt":"En esta ocasi\u00f3n, les ha tocado a la mitad de quinto A experimentar, trabajar y colaborar en el huerto escolar. [&hellip;]","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts\/4117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/comments?post=4117"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts\/4117\/revisions"}],"predecessor-version":[{"id":4119,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts\/4117\/revisions\/4119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/media\/4118"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/media?parent=4117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/categories?post=4117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/tags?post=4117"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/post_folder?post=4117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}