{"id":5074,"date":"2025-06-16T08:45:32","date_gmt":"2025-06-16T06:45:32","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/?p=5074"},"modified":"2025-06-16T08:45:32","modified_gmt":"2025-06-16T06:45:32","slug":"educacion-vial-en-las-aulas-de-p5","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/2025\/06\/16\/educacion-vial-en-las-aulas-de-p5\/","title":{"rendered":"Educaci\u00f3n vial en las aulas de P5"},"content":{"rendered":"<p>Vuelven nuestros polic\u00edas amigos y expertos en Ed. Vial para continuar su labor con los alumnos y alumnas de quinto.<\/p>\n<ul>\n<li><a href=\"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/galeria-de-fotos\/\" target=\"_blank\" rel=\"noopener\">Enlace a la galer\u00eda.<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Vuelven nuestros polic\u00edas amigos y expertos en Ed. Vial para continuar su labor con los alumnos y alumnas de quinto. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"post_folder":[],"class_list":["post-5074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quinto-de-primaria"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",850,425,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",850,425,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",850,425,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial-300x150.jpg",300,150,true],"large":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",850,425,false],"thumblist":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",500,250,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",850,425,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",850,425,false],"sydney-large-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",850,425,false],"sydney-medium-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",550,275,false],"sydney-small-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",230,115,false],"sydney-service-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",350,175,false],"sydney-mas-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",480,240,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",360,180,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",360,180,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2023\/11\/educacionvial.jpg",850,425,false]},"rttpg_author":{"display_name":"cp.navalazarza.sanagustin","author_link":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/author\/cuenta_cp-navalazarza-sanagustin\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/category\/quinto-de-primaria\/\" rel=\"category tag\">5\u00ba de Primaria<\/a>","rttpg_excerpt":"Vuelven nuestros polic\u00edas amigos y expertos en Ed. Vial para continuar su labor con los alumnos y alumnas de quinto. [&hellip;]","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts\/5074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/comments?post=5074"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts\/5074\/revisions"}],"predecessor-version":[{"id":5075,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts\/5074\/revisions\/5075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/media\/1558"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/media?parent=5074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/categories?post=5074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/tags?post=5074"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/post_folder?post=5074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}