{"id":6629,"date":"2026-03-02T09:00:59","date_gmt":"2026-03-02T08:00:59","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/?p=6629"},"modified":"2026-03-02T10:00:49","modified_gmt":"2026-03-02T09:00:49","slug":"actualizacion-sobre-la-nueva-normativa-de-comedores-escolares","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/2026\/03\/02\/actualizacion-sobre-la-nueva-normativa-de-comedores-escolares\/","title":{"rendered":"Actualizaci\u00f3n sobre la nueva normativa de comedores escolares"},"content":{"rendered":"\n<p>El colegio informa a las familias de la entrada en vigor del <strong>Real Decreto 315\/2025<\/strong>, que actualiza la normativa de seguridad alimentaria y nutrici\u00f3n en los comedores escolares. Tal como recoge el comunicado, esta regulaci\u00f3n busca <em>\u201cfavorecer men\u00fas m\u00e1s equilibrados y sostenibles en los comedores escolares\u201d<\/em> y establece nuevas frecuencias de consumo para los distintos grupos de alimentos.<\/p>\n\n\n\n<p>Sodexo ya est\u00e1 trabajando en la adaptaci\u00f3n progresiva de los men\u00fas, con la colaboraci\u00f3n de dietistas y nutricionistas, la selecci\u00f3n de productos frescos y de temporada y una comunicaci\u00f3n transparente con las familias. Seg\u00fan el documento, el objetivo es que el alumnado <em>\u201cdisfrute de men\u00fas variados y equilibrados, dise\u00f1ados para cubrir sus necesidades nutricionales\u201d<\/em> mientras se fomenta un entorno m\u00e1s saludable y sostenible.Los cambios se ir\u00e1n implantando de forma gradual hasta abril de 2027. <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2026\/02\/Comunicado-familias-Real-Decreto-comedores-escolares.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Leer documento<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El colegio informa a las familias de la entrada en vigor del Real Decreto 315\/2025, que actualiza la normativa de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2331,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"post_folder":[],"class_list":["post-6629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-todos-los-cursos"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor.jpg",850,425,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor.jpg",850,425,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor.jpg",850,425,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor-300x150.jpg",300,150,true],"large":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor.jpg",850,425,false],"thumblist":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor.jpg",500,250,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor.jpg",850,425,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor.jpg",850,425,false],"sydney-large-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor.jpg",850,425,false],"sydney-medium-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor-550x400.jpg",550,400,true],"sydney-small-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor-230x115.jpg",230,115,true],"sydney-service-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor-350x175.jpg",350,175,true],"sydney-mas-thumb":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor-480x240.jpg",480,240,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor.jpg",360,180,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor.jpg",360,180,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/\/wp-content\/uploads\/cp.navalazarza.sanagustin\/2024\/06\/imagen-becas-comedor.jpg",850,425,false]},"rttpg_author":{"display_name":"cp.navalazarza.sanagustin","author_link":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/author\/cuenta_cp-navalazarza-sanagustin\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/category\/todos-los-cursos\/\" rel=\"category tag\">Todos los cursos<\/a>","rttpg_excerpt":"El colegio informa a las familias de la entrada en vigor del Real Decreto 315\/2025, que actualiza la normativa de [&hellip;]","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts\/6629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/comments?post=6629"}],"version-history":[{"count":2,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts\/6629\/revisions"}],"predecessor-version":[{"id":6632,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/posts\/6629\/revisions\/6632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/media\/2331"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/media?parent=6629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/categories?post=6629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/tags?post=6629"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.navalazarza.sanagustin\/index.php\/wp-json\/wp\/v2\/post_folder?post=6629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}