{"id":532,"date":"2019-11-14T08:38:16","date_gmt":"2019-11-14T08:38:16","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/?p=532"},"modified":"2020-02-06T08:23:10","modified_gmt":"2020-02-06T08:23:10","slug":"lectura-del-libro-del-museo-del-prado","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/2019\/11\/14\/lectura-del-libro-del-museo-del-prado\/","title":{"rendered":"Lectura del libro del Museo del Prado"},"content":{"rendered":"\n<p style=\"font-size:20px\">Nada mejor que conocer con anterioridad lo que se va a ver despu\u00e9s para poder apreciar en todo su esplendor lo que nos rodea. <\/p>\n\n\n\n<p style=\"font-size:20px\">Para ello, nuestros alumnos se han imbuido en la lectura del libro sobre el Museo del Prado haciendo que lleven en mente lo que luego ver\u00e1n en directo.<\/p>\n\n\n\n<p style=\"font-size:20px\">Una bonita y enriquecedora experiencia que les abre las puertas al mundo del arte.<\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-1 wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22-1-1024x768.jpeg\" alt=\"\" data-id=\"522\" data-link=\"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/2020\/01\/10\/creacion-de-marionetas\/whatsapp-image-2020-01-29-at-08-31-22-1\/\" class=\"wp-image-522\" srcset=\"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22-1-1024x768.jpeg 1024w, https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22-1-300x225.jpeg 300w, https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22-1-768x576.jpeg 768w, https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22-1.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Nada mejor que conocer con anterioridad lo que se va a ver despu\u00e9s para poder apreciar en todo su esplendor lo que nos rodea. Para ello, nuestros alumnos se han imbuido en la lectura del libro sobre el Museo del Prado haciendo que lleven en mente lo que luego ver\u00e1n en directo. Una bonita y&#8230;<\/p>\n","protected":false},"author":2,"featured_media":523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[8],"post_folder":[],"class_list":["post-532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-escolares","tag-actividades-2019-2020"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22.jpeg",1600,1200,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22.jpeg",1600,1200,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22.jpeg",1600,1200,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22-150x150.jpeg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22-300x225.jpeg",300,225,true],"large":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22-1024x768.jpeg",640,480,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22.jpeg",300,225,false],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22.jpeg",500,375,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22.jpeg",432,324,false],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22.jpeg",347,260,false],"tileview":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22.jpeg",300,225,false],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22.jpeg",1536,1152,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22.jpeg",1600,1200,false],"post-thumbnail":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22-320x216.jpeg",320,216,true],"kids-education-gallery-section-small":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22-300x300.jpeg",300,300,true],"kids-education-related-posts-image":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22-400x200.jpeg",400,200,true],"kids-education-blog-images":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22-175x230.jpeg",175,230,true],"kids-education-archive-search-image":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22-350x265.jpeg",350,265,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22.jpeg",243,182,false],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22.jpeg",360,270,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22.jpeg",320,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/\/wp-content\/uploads\/cp.nunezdebalboa.madrid\/2020\/01\/WhatsApp-Image-2020-01-29-at-08.31.22.jpeg",1600,1200,false]},"rttpg_author":{"display_name":"tic.cp.nunezdebalboa.madrid","author_link":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/author\/cuenta_tic-cp-nunezdebalboa-madrid\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/category\/actividades-escolares\/\" rel=\"category tag\">Actividades Escolares<\/a>","rttpg_excerpt":"Nada mejor que conocer con anterioridad lo que se va a ver despu\u00e9s para poder apreciar en todo su esplendor lo que nos rodea. Para ello, nuestros alumnos se han imbuido en la lectura del libro sobre el Museo del Prado haciendo que lleven en mente lo que luego ver\u00e1n en directo. Una bonita y...","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/wp-json\/wp\/v2\/posts\/532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=532"}],"version-history":[{"count":3,"href":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/wp-json\/wp\/v2\/posts\/532\/revisions"}],"predecessor-version":[{"id":538,"href":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/wp-json\/wp\/v2\/posts\/532\/revisions\/538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/wp-json\/wp\/v2\/media\/523"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/wp-json\/wp\/v2\/categories?post=532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=532"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.nunezdebalboa.madrid\/index.php\/wp-json\/wp\/v2\/post_folder?post=532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}