{"id":1935,"date":"2022-05-18T16:25:47","date_gmt":"2022-05-18T14:25:47","guid":{"rendered":"https:\/\/seisdediciembre.com\/?p=1935"},"modified":"2023-04-21T10:32:28","modified_gmt":"2023-04-21T08:32:28","slug":"inscripcion-al-servicio-de-tardes","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/2022\/05\/18\/inscripcion-al-servicio-de-tardes\/","title":{"rendered":"Inscripci\u00f3n Ampliaci\u00f3n Servicio de tarde"},"content":{"rendered":"\n<p><b>Los usuarios que quieran utilizar \u00e9ste servicio, deber\u00e1n rellenar la solicitud y entregarla junto con la copia de ingreso de transferencia, a las personas responsables de COCINAS CENTRALES y antes del 27 de mayo de 2022.<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/18-Tardes-CEIP-Seis-de-DiciembreJUNIO-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:1070px\" aria-label=\"Incrustado de Incrustado de 18 Tardes CEIP Seis de DiciembreJUNIO (1)..\"><\/object><a id=\"wp-block-file--media-9351d86b-9e38-414c-9322-6361c95850eb\" href=\"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/18-Tardes-CEIP-Seis-de-DiciembreJUNIO-1.pdf\">18 Tardes CEIP Seis de DiciembreJUNIO (1)<\/a><a href=\"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/18-Tardes-CEIP-Seis-de-DiciembreJUNIO-1.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-9351d86b-9e38-414c-9322-6361c95850eb\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los usuarios que quieran utilizar \u00e9ste servicio, deber\u00e1n rellenar la solicitud y entregarla junto con la copia de ingreso de transferencia, a [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":1937,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"post_folder":[],"class_list":["post-1935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde.jpg",1296,910,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde.jpg",1296,910,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde.jpg",1296,910,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde-300x211.jpg",300,211,true],"large":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde-1024x719.jpg",1024,719,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde.jpg",500,351,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde.jpg",1296,910,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde.jpg",1296,910,false],"sydney-large-thumb":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde.jpg",1000,702,false],"sydney-medium-thumb":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde.jpg",550,386,false],"sydney-small-thumb":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde.jpg",230,161,false],"sydney-service-thumb":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde.jpg",350,246,false],"sydney-mas-thumb":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde.jpg",480,337,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde.jpg",360,253,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde.jpg",342,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/05\/inscripcionserviciotarde.jpg",1296,910,false]},"rttpg_author":{"display_name":"Colegio","author_link":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/author\/colegio\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/category\/novedades\/\" rel=\"category tag\">Novedades<\/a>","rttpg_excerpt":"Los usuarios que quieran utilizar \u00e9ste servicio, deber\u00e1n rellenar la solicitud y entregarla junto con la copia de ingreso de transferencia, a [&hellip;]","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/posts\/1935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/comments?post=1935"}],"version-history":[{"count":2,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/posts\/1935\/revisions"}],"predecessor-version":[{"id":2924,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/posts\/1935\/revisions\/2924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/media\/1937"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/media?parent=1935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/categories?post=1935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/tags?post=1935"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/post_folder?post=1935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}