{"id":2081,"date":"2022-10-21T14:16:24","date_gmt":"2022-10-21T12:16:24","guid":{"rendered":"https:\/\/seisdediciembre.com\/?p=2081"},"modified":"2023-04-21T10:24:06","modified_gmt":"2023-04-21T08:24:06","slug":"2a-exposicion-de-calabazas","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/2022\/10\/21\/2a-exposicion-de-calabazas\/","title":{"rendered":"2\u00aa Exposici\u00f3n de calabazas"},"content":{"rendered":"\n<p>Decora y trae tu calabaza m\u00e1s terror\u00edfica para la exposici\u00f3n de calabazas del AMPA.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1344\" src=\"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg\" alt=\"\" class=\"wp-image-2077\" srcset=\"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg 1920w, https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073-300x210.jpg 300w, https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073-1024x717.jpg 1024w, https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073-768x538.jpg 768w, https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073-1536x1075.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Decora y trae tu calabaza m\u00e1s terror\u00edfica para la exposici\u00f3n de calabazas del AMPA.<\/p>\n","protected":false},"author":9,"featured_media":2077,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"post_folder":[],"class_list":["post-2081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg",1920,1344,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg",1920,1344,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg",1920,1344,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073-300x210.jpg",300,210,true],"large":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073-1024x717.jpg",1024,717,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg",500,350,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073-1536x1075.jpg",1536,1075,true],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg",1920,1344,false],"sydney-large-thumb":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg",1000,700,false],"sydney-medium-thumb":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg",550,385,false],"sydney-small-thumb":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg",230,161,false],"sydney-service-thumb":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg",350,245,false],"sydney-mas-thumb":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg",480,336,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg",360,252,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg",343,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/\/wp-content\/uploads\/cp.seisdediciembre.torrejondeardoz\/2022\/10\/InShot_20221020_123240073.jpg",1920,1344,false]},"rttpg_author":{"display_name":"Colegio","author_link":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/author\/colegio\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/category\/novedades\/\" rel=\"category tag\">Novedades<\/a>","rttpg_excerpt":"Decora y trae tu calabaza m\u00e1s terror\u00edfica para la exposici\u00f3n de calabazas del AMPA.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/posts\/2081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/comments?post=2081"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/posts\/2081\/revisions"}],"predecessor-version":[{"id":2880,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/posts\/2081\/revisions\/2880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/media\/2077"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/media?parent=2081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/categories?post=2081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/tags?post=2081"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.seisdediciembre.torrejondeardoz\/index.php\/wp-json\/wp\/v2\/post_folder?post=2081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}