{"id":1277,"date":"2023-09-03T19:38:21","date_gmt":"2023-09-03T17:38:21","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/?p=1277"},"modified":"2023-09-03T19:39:36","modified_gmt":"2023-09-03T17:39:36","slug":"alumnos-con-necesidad-especifica-de-apoyo-educativo-solicitud-de-ayuda-hasta-el-20-de-septiembre","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/2023\/09\/03\/alumnos-con-necesidad-especifica-de-apoyo-educativo-solicitud-de-ayuda-hasta-el-20-de-septiembre\/","title":{"rendered":"Alumnos con Necesidad Espec\u00edfica de Apoyo Educativo. Solicitud de ayuda hasta el 20 de septiembre"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.educacionyfp.gob.es\/servicios-al-ciudadano\/catalogo\/estudiantes\/becas-ayudas\/para-estudiar\/deportivas\/necesidad-especifica-apoyo-educativo.html\" target=\"_blank\" rel=\"noreferrer noopener\">Enlace a la p\u00e1gina para la realizaci\u00f3n de los tr\u00e1mites<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enlace a la p\u00e1gina para la realizaci\u00f3n de los tr\u00e1mites<\/p>\n","protected":false},"author":3,"featured_media":1267,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"post_folder":[],"class_list":["post-1277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-para-familias"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas.jpg",612,408,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas.jpg",612,408,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas.jpg",612,408,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas-300x200.jpg",300,200,true],"large":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas.jpg",612,408,false],"thumblist":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas.jpg",500,333,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas.jpg",612,408,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas.jpg",612,408,false],"total-portfolio-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas-400x400.jpg",400,400,true],"total-team-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas-350x408.jpg",350,408,true],"total-blog-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas-400x280.jpg",400,280,true],"total-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas-100x100.jpg",100,100,true],"total-blog-header":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas-612x360.jpg",612,360,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas.jpg",360,240,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas.jpg",360,240,false],"sow-blog-portfolio":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas-375x375.jpg",375,375,true],"sow-blog-grid":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas.jpg",612,408,false],"sow-blog-alternate":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas.jpg",612,408,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Becas.jpg",612,408,false]},"rttpg_author":{"display_name":"cp.soledadsainz.colmenarviejo","author_link":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/author\/cuenta_cp-soledadsainz-colmenarviejo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/category\/informacion-para-familias\/\" rel=\"category tag\">Informaci\u00f3n para familias<\/a>","rttpg_excerpt":"Enlace a la p\u00e1gina para la realizaci\u00f3n de los tr\u00e1mites","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/comments?post=1277"}],"version-history":[{"count":3,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1277\/revisions"}],"predecessor-version":[{"id":1280,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1277\/revisions\/1280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/media\/1267"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/media?parent=1277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/categories?post=1277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/tags?post=1277"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/post_folder?post=1277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}