{"id":1710,"date":"2023-11-28T18:55:20","date_gmt":"2023-11-28T17:55:20","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/?p=1710"},"modified":"2023-11-28T18:56:00","modified_gmt":"2023-11-28T17:56:00","slug":"celebramos-el-25n-dia-internacional-de-la-eliminacion-de-la-violencia-contra-la-mujer","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/2023\/11\/28\/celebramos-el-25n-dia-internacional-de-la-eliminacion-de-la-violencia-contra-la-mujer\/","title":{"rendered":"Celebramos el 25N: D\u00eda Internacional de la eliminaci\u00f3n de la Violencia contra la Mujer"},"content":{"rendered":"<p>Un a\u00f1o m\u00e1s, abordamos con nuestro alumnado la importancia de la eliminaci\u00f3n de la violencia, de cualquier tipo, en especial, el d\u00eda 25 de noviembre, la eliminaci\u00f3n de la Violencia contra la Mujer.<\/p>\n<p>Este a\u00f1o lo hemos hecho bajo el lema \u00abEl latido de las mariposas\u00bb con el cuento, <a href=\"https:\/\/www.youtube.com\/watch?v=I_85yOGZ5SE\">Nerea y Martina y el latido de las mariposas<\/a>.<\/p>\n<p>&nbsp;<\/p>\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1001\" data-id=\"1713\" src=\"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/1701192156522-1024x1001.jpg\" alt=\"\" class=\"wp-image-1713\" srcset=\"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/1701192156522-1024x1001.jpg 1024w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/1701192156522-300x293.jpg 300w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/1701192156522-768x750.jpg 768w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/1701192156522-1536x1501.jpg 1536w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/1701192156522.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"771\" data-id=\"1714\" src=\"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/1701192156502-1024x771.jpg\" alt=\"\" class=\"wp-image-1714\" srcset=\"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/1701192156502-1024x771.jpg 1024w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/1701192156502-300x226.jpg 300w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/1701192156502-768x578.jpg 768w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/1701192156502-1536x1157.jpg 1536w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/1701192156502-2048x1542.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Un a\u00f1o m\u00e1s, abordamos con nuestro alumnado la importancia de la eliminaci\u00f3n de la violencia, de cualquier tipo, en especial, el d\u00eda 25 de noviembre, la eliminaci\u00f3n de la Violencia contra la Mujer. Este a\u00f1o lo hemos hecho bajo el lema \u00abEl latido de las mariposas\u00bb con el cuento, Nerea y Martina y el latido [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1711,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"post_folder":[],"class_list":["post-1710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades-del-cole"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617.jpg",2481,2482,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617.jpg",2481,2482,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617.jpg",2481,2482,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-300x300.jpg",300,300,true],"large":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-1024x1024.jpg",640,640,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617.jpg",500,500,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-1536x1536.jpg",1536,1536,true],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-2048x2048.jpg",2048,2048,true],"total-portfolio-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-400x400.jpg",400,400,true],"total-team-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-350x420.jpg",350,420,true],"total-blog-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-400x280.jpg",400,280,true],"total-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-100x100.jpg",100,100,true],"total-blog-header":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-720x360.jpg",720,360,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617.jpg",360,360,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617.jpg",240,240,false],"sow-blog-portfolio":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-375x375.jpg",375,375,true],"sow-blog-grid":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-720x480.jpg",720,480,true],"sow-blog-alternate":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617-950x630.jpg",950,630,true],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/11\/b9931c9f-4c86-4e57-8226-9b870351b617.jpg",2481,2482,false]},"rttpg_author":{"display_name":"cp.soledadsainz.colmenarviejo","author_link":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/author\/cuenta_cp-soledadsainz-colmenarviejo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/category\/novedades-del-cole\/\" rel=\"category tag\">Novedades del cole<\/a>","rttpg_excerpt":"Un a\u00f1o m\u00e1s, abordamos con nuestro alumnado la importancia de la eliminaci\u00f3n de la violencia, de cualquier tipo, en especial, el d\u00eda 25 de noviembre, la eliminaci\u00f3n de la Violencia contra la Mujer. Este a\u00f1o lo hemos hecho bajo el lema \u00abEl latido de las mariposas\u00bb con el cuento, Nerea y Martina y el latido&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/comments?post=1710"}],"version-history":[{"count":2,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1710\/revisions"}],"predecessor-version":[{"id":1715,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1710\/revisions\/1715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/media\/1711"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/media?parent=1710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/categories?post=1710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/tags?post=1710"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/post_folder?post=1710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}