{"id":1851,"date":"2024-04-25T14:24:28","date_gmt":"2024-04-25T12:24:28","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/?p=1851"},"modified":"2024-04-26T09:42:09","modified_gmt":"2024-04-26T07:42:09","slug":"noche-en-el-colegio-17-de-mayo","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/2024\/04\/25\/noche-en-el-colegio-17-de-mayo\/","title":{"rendered":"Noche en el colegio (17 de mayo)"},"content":{"rendered":"<p>El pr\u00f3ximo 17 de mayo pasaremos una noche m\u00e1gica en el colegio aprendiendo un mont\u00f3n de cosas sobre el Universo.<\/p>\n<p>Desde las <strong>19:00 horas del viernes 17 de mayo hasta las 10:30 horas del s\u00e1bado 18,<\/strong> el alumnado del Soledad Sainz de<strong> 2\u00ba a 5\u00ba<\/strong> de Primaria que quiera, puede quedarse en el colegio a dormir y disfrutar de las actividades organizadas por el AMPA.<\/p>\n<p>Para ello el centro contar\u00e1 con monitores\/monitoras, profesores del centro y familias del AMPA que estar\u00e1n en todo momento con el alumnado.<\/p>\n<p>La actividad es GRATUITA e incluye:<\/p>\n<p>\u2022 1 Noche durmiendo en el colegio<br \/>\n\u2022 Programa completo de actividades<br \/>\n\u2022 Telescopios<br \/>\n\u2022 Equipo de monitores y coordinador<br \/>\n\u2022 Desayuno de los participantes<\/p>\n<p>\u00bfQU\u00c9 TIENE QUE LLEVAR MI HIJO\/HIJA?<\/p>\n<p>Una mochila con su nombre en la que lleve agua y cena tipo picnic.<\/p>\n<p>Deben ir con ropa c\u00f3moda.<\/p>\n<p>Saco de dormir o mantas<\/p>\n<p>Cena del viernes<\/p>\n<p>Consulta el dossier con las actividades, horarios y material necesario <strong><a href=\"https:\/\/drive.google.com\/file\/d\/1A5TLlLZTo4gVnaDP-qdDUmTZGrN6TxF5\/view?usp=sharing\">aqu\u00ed<\/a><\/strong><\/p>\n<p>An\u00edmate a vivir esta experiencia con nosotros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo 17 de mayo pasaremos una noche m\u00e1gica en el colegio aprendiendo un mont\u00f3n de cosas sobre el Universo. Desde las 19:00 horas del viernes 17 de mayo hasta las 10:30 horas del s\u00e1bado 18, el alumnado del Soledad Sainz de 2\u00ba a 5\u00ba de Primaria que quiera, puede quedarse en el colegio a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1852,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"post_folder":[],"class_list":["post-1851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-para-familias"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image.png",564,436,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image.png",564,436,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image.png",564,436,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image-150x150.png",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image-300x232.png",300,232,true],"large":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image.png",564,436,false],"thumblist":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image-300x300.png",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image.png",500,387,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image-474x324.png",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image-391x260.png",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image-300x400.png",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image.png",564,436,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image.png",564,436,false],"total-portfolio-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image-400x400.png",400,400,true],"total-team-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image-350x420.png",350,420,true],"total-blog-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image-400x280.png",400,280,true],"total-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image-100x100.png",100,100,true],"total-blog-header":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image-564x360.png",564,360,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image-272x182.png",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image.png",360,278,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image.png",310,240,false],"sow-blog-portfolio":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image-375x375.png",375,375,true],"sow-blog-grid":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image.png",564,436,false],"sow-blog-alternate":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image.png",564,436,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/04\/image.png",564,436,false]},"rttpg_author":{"display_name":"cp.soledadsainz.colmenarviejo","author_link":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/author\/cuenta_cp-soledadsainz-colmenarviejo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/category\/informacion-para-familias\/\" rel=\"category tag\">Informaci\u00f3n para familias<\/a>","rttpg_excerpt":"El pr\u00f3ximo 17 de mayo pasaremos una noche m\u00e1gica en el colegio aprendiendo un mont\u00f3n de cosas sobre el Universo. Desde las 19:00 horas del viernes 17 de mayo hasta las 10:30 horas del s\u00e1bado 18, el alumnado del Soledad Sainz de 2\u00ba a 5\u00ba de Primaria que quiera, puede quedarse en el colegio a&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/comments?post=1851"}],"version-history":[{"count":2,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1851\/revisions"}],"predecessor-version":[{"id":1855,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1851\/revisions\/1855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/media\/1852"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/media?parent=1851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/categories?post=1851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/tags?post=1851"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/post_folder?post=1851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}