{"id":1997,"date":"2024-09-04T17:51:01","date_gmt":"2024-09-04T15:51:01","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/?p=1997"},"modified":"2024-09-04T17:51:44","modified_gmt":"2024-09-04T15:51:44","slug":"programa-de-desayunos-saludables-planning-semanal","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/2024\/09\/04\/programa-de-desayunos-saludables-planning-semanal\/","title":{"rendered":"Programa de desayunos saludables (Planning semanal)"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/DESAYUNOS-DEL-COLE-CIRCULAR-6_page-0001-724x1024.jpg\" alt=\"\" class=\"wp-image-2000\" srcset=\"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/DESAYUNOS-DEL-COLE-CIRCULAR-6_page-0001-724x1024.jpg 724w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/DESAYUNOS-DEL-COLE-CIRCULAR-6_page-0001-212x300.jpg 212w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/DESAYUNOS-DEL-COLE-CIRCULAR-6_page-0001-768x1086.jpg 768w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/DESAYUNOS-DEL-COLE-CIRCULAR-6_page-0001-1086x1536.jpg 1086w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/DESAYUNOS-DEL-COLE-CIRCULAR-6_page-0001.jpg 1241w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":1998,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"post_folder":[],"class_list":["post-1997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-para-familias"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable.jpg",1283,855,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable.jpg",1283,855,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable.jpg",1283,855,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-300x200.jpg",300,200,true],"large":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-1024x682.jpg",640,426,true],"thumblist":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-500x500.jpg",500,500,true],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable.jpg",1283,855,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable.jpg",1283,855,false],"total-portfolio-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-400x400.jpg",400,400,true],"total-team-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-350x420.jpg",350,420,true],"total-blog-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-400x280.jpg",400,280,true],"total-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-100x100.jpg",100,100,true],"total-blog-header":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-720x360.jpg",720,360,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable.jpg",360,240,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable.jpg",360,240,false],"sow-blog-portfolio":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-375x375.jpg",375,375,true],"sow-blog-grid":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-720x480.jpg",720,480,true],"sow-blog-alternate":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable-950x630.jpg",950,630,true],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2024\/09\/Desayuno-saludable.jpg",1283,855,false]},"rttpg_author":{"display_name":"cp.soledadsainz.colmenarviejo","author_link":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/author\/cuenta_cp-soledadsainz-colmenarviejo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/category\/informacion-para-familias\/\" rel=\"category tag\">Informaci\u00f3n para familias<\/a>","rttpg_excerpt":null,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/comments?post=1997"}],"version-history":[{"count":2,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1997\/revisions"}],"predecessor-version":[{"id":2001,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/1997\/revisions\/2001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/media\/1998"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/media?parent=1997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/categories?post=1997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/tags?post=1997"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/post_folder?post=1997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}