{"id":2220,"date":"2025-01-27T11:48:35","date_gmt":"2025-01-27T10:48:35","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/?p=2220"},"modified":"2025-01-29T09:28:23","modified_gmt":"2025-01-29T08:28:23","slug":"menu-comedor-escolar-febrero-2025","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/2025\/01\/27\/menu-comedor-escolar-febrero-2025\/","title":{"rendered":"Men\u00fa comedor escolar febrero 2025"},"content":{"rendered":"<ul>\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/1CB3HuSqjsk5ByPOHtQKEpToqjD1JukyT\/view?usp=drive_link\">Men\u00fa comedor febrero<\/a><\/li>\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/1jrSeyrPG6r-5zsb_PIypcDsk9K2e7wRs\/view?usp=drive_link\">Men\u00fa alergias febrero<\/a><\/li>\n<\/ul>\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"725\" height=\"1024\" src=\"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2025\/01\/07-Febrero-CEIP-Soledad-Sainz-_page-0002-725x1024.jpg\" alt=\"\" class=\"wp-image-2222\" srcset=\"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2025\/01\/07-Febrero-CEIP-Soledad-Sainz-_page-0002-725x1024.jpg 725w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2025\/01\/07-Febrero-CEIP-Soledad-Sainz-_page-0002-212x300.jpg 212w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2025\/01\/07-Febrero-CEIP-Soledad-Sainz-_page-0002-768x1085.jpg 768w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2025\/01\/07-Febrero-CEIP-Soledad-Sainz-_page-0002-1087x1536.jpg 1087w, https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2025\/01\/07-Febrero-CEIP-Soledad-Sainz-_page-0002.jpg 1241w\" sizes=\"auto, (max-width: 725px) 100vw, 725px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Men\u00fa comedor febrero Men\u00fa alergias febrero<\/p>\n","protected":false},"author":3,"featured_media":1271,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"post_folder":[],"class_list":["post-2220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-para-familias"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor.jpg",612,436,false],"landscape":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor.jpg",612,436,false],"portraits":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor.jpg",612,436,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor-300x214.jpg",300,214,true],"large":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor.jpg",612,436,false],"thumblist":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor.jpg",500,356,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor.jpg",612,436,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor.jpg",612,436,false],"total-portfolio-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor-400x400.jpg",400,400,true],"total-team-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor-350x420.jpg",350,420,true],"total-blog-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor-400x280.jpg",400,280,true],"total-thumb":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor-100x100.jpg",100,100,true],"total-blog-header":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor-612x360.jpg",612,360,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor.jpg",360,256,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor.jpg",337,240,false],"sow-blog-portfolio":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor-375x375.jpg",375,375,true],"sow-blog-grid":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor.jpg",612,436,false],"sow-blog-alternate":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor.jpg",612,436,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/\/wp-content\/uploads\/cp.soledadsainz.colmenarviejo\/2023\/09\/Comedor.jpg",612,436,false]},"rttpg_author":{"display_name":"cp.soledadsainz.colmenarviejo","author_link":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/author\/cuenta_cp-soledadsainz-colmenarviejo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/category\/informacion-para-familias\/\" rel=\"category tag\">Informaci\u00f3n para familias<\/a>","rttpg_excerpt":"Men\u00fa comedor febrero Men\u00fa alergias febrero","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/2220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/comments?post=2220"}],"version-history":[{"count":3,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/2220\/revisions"}],"predecessor-version":[{"id":2225,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/posts\/2220\/revisions\/2225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/media\/1271"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/media?parent=2220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/categories?post=2220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/tags?post=2220"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cp.soledadsainz.colmenarviejo\/index.php\/wp-json\/wp\/v2\/post_folder?post=2220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}