{"id":5360,"date":"2025-02-15T11:25:02","date_gmt":"2025-02-15T10:25:02","guid":{"rendered":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/?p=5360"},"modified":"2025-02-19T11:38:11","modified_gmt":"2025-02-19T10:38:11","slug":"audicion-de-alumnos-de-piano-profesor-carlos-j-dominguez-jueves-20-de-febrero-1930h-salon-de-actos","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/2025\/02\/15\/audicion-de-alumnos-de-piano-profesor-carlos-j-dominguez-jueves-20-de-febrero-1930h-salon-de-actos\/","title":{"rendered":"Audici\u00f3n de alumnos de piano. Profesor: Carlos J. Dom\u00ednguez. Jueves, 20 de Febrero. 19:30h. Sal\u00f3n de actos."},"content":{"rendered":"\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-2ce7f15f-5ec9-4c45-94b3-0d099ceba123\" href=\"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2025\/02\/Piano-20-febrero-2025-Carlos.pdf\">PROGRAMA<\/a><a href=\"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2025\/02\/Piano-20-febrero-2025-Carlos.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-2ce7f15f-5ec9-4c45-94b3-0d099ceba123\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":5333,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-5360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero.jpg",794,794,false],"landscape":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero.jpg",794,794,false],"portraits":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero.jpg",794,794,false],"thumbnail":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero-300x300.jpg",300,300,true],"large":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero.jpg",696,696,false],"thumblist":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero-500x500.jpg",500,500,true],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero.jpg",794,794,false],"2048x2048":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero.jpg",794,794,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero.jpg",360,360,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero.jpg",240,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/\/wp-content\/uploads\/cpm.adolfosalazar.madrid\/2024\/10\/Carlos-20-Febrero.jpg",794,794,false]},"rttpg_author":{"display_name":"cpm.adolfosalazar.madrid","author_link":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/author\/cuenta_cpm-adolfosalazar-madrid\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":null,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/wp-json\/wp\/v2\/posts\/5360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=5360"}],"version-history":[{"count":3,"href":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/wp-json\/wp\/v2\/posts\/5360\/revisions"}],"predecessor-version":[{"id":5372,"href":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/wp-json\/wp\/v2\/posts\/5360\/revisions\/5372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/wp-json\/wp\/v2\/media\/5333"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=5360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/wp-json\/wp\/v2\/categories?post=5360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=5360"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/cpm.adolfosalazar.madrid\/index.php\/wp-json\/wp\/v2\/post_folder?post=5360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}