{"id":8167,"date":"2024-04-15T14:26:57","date_gmt":"2024-04-15T12:26:57","guid":{"rendered":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/?p=8167"},"modified":"2024-04-15T14:29:50","modified_gmt":"2024-04-15T12:29:50","slug":"admision-2o-cuatrimestre-prueba-2-2-2-2-2-2-2-2-2-3-2-2-2-3-2-3","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/2024\/04\/15\/admision-2o-cuatrimestre-prueba-2-2-2-2-2-2-2-2-2-3-2-2-2-3-2-3\/","title":{"rendered":"22 al 30 de abril"},"content":{"rendered":"<div id=\"pl-8167\"  class=\"panel-layout\" ><div id=\"pg-8167-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-8167-0-0\"  class=\"panel-grid-cell panel-grid-cell-mobile-last\" ><div id=\"panel-8167-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" ><h3 class=\"widget-title\">SEMANA CULTURAL<\/h3>\t\t\t<div class=\"textwidget\"><p>M\u00fasica, recitales, libros, exposiciones&#8230;<br \/>\nEOI Madrid-Jes\u00fas Maestro<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n\t\t<\/div><\/div><div id=\"pgc-8167-0-1\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>M\u00fasica, recitales, libros, exposiciones&#8230; EOI Madrid-Jes\u00fas Maestro &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":8168,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"footnotes":""},"categories":[14],"tags":[],"post_folder":[],"class_list":["post-8167","post","type-post","status-publish","format-aside","has-post-thumbnail","hentry","category-actividades","post_format-post-format-aside"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview.png",1024,1448,false],"landscape":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview.png",1024,1448,false],"portraits":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview.png",1024,1448,false],"thumbnail":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview-150x150.png",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview-212x300.png",212,300,true],"large":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview-724x1024.png",525,743,true],"thumblist":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview-300x300.png",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview.png",354,500,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview-474x324.png",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview-391x260.png",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview-300x400.png",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview.png",1024,1448,false],"2048x2048":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview.png",1024,1448,false],"twentyseventeen-featured-image":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview-1024x1200.png",1024,1200,true],"twentyseventeen-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview-100x100.png",100,100,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview-272x182.png",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview.png",337,476,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview.png",170,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/\/wp-content\/uploads\/eoi.jesusmaestro.madrid\/2024\/04\/designPreview.png",1024,1448,false]},"rttpg_author":{"display_name":"eoi.jesusmaestro.madrid","author_link":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/author\/cuenta_eoi-jesusmaestro-madrid\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/category\/actividades\/\" rel=\"category tag\">Actividades<\/a>","rttpg_excerpt":"M\u00fasica, recitales, libros, exposiciones... EOI Madrid-Jes\u00fas Maestro &nbsp;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/wp-json\/wp\/v2\/posts\/8167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=8167"}],"version-history":[{"count":2,"href":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/wp-json\/wp\/v2\/posts\/8167\/revisions"}],"predecessor-version":[{"id":8170,"href":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/wp-json\/wp\/v2\/posts\/8167\/revisions\/8170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/wp-json\/wp\/v2\/media\/8168"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=8167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/wp-json\/wp\/v2\/categories?post=8167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=8167"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/eoi.jesusmaestro.madrid\/index.php\/wp-json\/wp\/v2\/post_folder?post=8167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}