{"id":2651,"date":"2025-01-17T13:35:16","date_gmt":"2025-01-17T12:35:16","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/?p=2651"},"modified":"2025-01-17T13:35:16","modified_gmt":"2025-01-17T12:35:16","slug":"informacion-de-la-reunion-de-inmersion-linguistica","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/2025\/01\/17\/informacion-de-la-reunion-de-inmersion-linguistica\/","title":{"rendered":"INFORMACI\u00d3N DE LA REUNI\u00d3N DE INMERSI\u00d3N LING\u00dcISTICA"},"content":{"rendered":"<p>En el siguiente documento encontrareis toda la informaci\u00f3n sobre el viaje de 1\u00ba y 2\u00ba ESO<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/\/wp-content\/uploads\/ies.anselmolorenzo.sanmartindelavega\/2025\/01\/INFORMACION-16-DE-ENERO.pdf\">INFORMACI\u00d3N 16 DE ENERO<\/a><\/p>\n<p>Adem\u00e1s, en la p\u00e1gina de <a href=\"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/actividades-extraescolares\/\">Actividades Extraescolares<\/a> ten\u00e9is disponible la presentaci\u00f3n de la empresa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el siguiente documento encontrareis toda la informaci\u00f3n sobre el viaje de 1\u00ba y 2\u00ba ESO INFORMACI\u00d3N 16 DE ENERO Adem\u00e1s, en la p\u00e1gina de Actividades Extraescolares ten\u00e9is disponible la presentaci\u00f3n de la empresa<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-2651","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"tic.ies.anselmolorenzo.sanmartindelavega","author_link":"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/author\/cuenta_tic-ies-anselmolorenzo-sanmartindelavega\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"En el siguiente documento encontrareis toda la informaci\u00f3n sobre el viaje de 1\u00ba y 2\u00ba ESO INFORMACI\u00d3N 16 DE ENERO Adem\u00e1s, en la p\u00e1gina de Actividades Extraescolares ten\u00e9is disponible la presentaci\u00f3n de la empresa","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/wp-json\/wp\/v2\/posts\/2651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/wp-json\/wp\/v2\/comments?post=2651"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/wp-json\/wp\/v2\/posts\/2651\/revisions"}],"predecessor-version":[{"id":2653,"href":"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/wp-json\/wp\/v2\/posts\/2651\/revisions\/2653"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/wp-json\/wp\/v2\/media?parent=2651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/wp-json\/wp\/v2\/categories?post=2651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/wp-json\/wp\/v2\/tags?post=2651"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.anselmolorenzo.sanmartindelavega\/index.php\/wp-json\/wp\/v2\/post_folder?post=2651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}