{"id":11934,"date":"2025-09-12T23:09:08","date_gmt":"2025-09-12T21:09:08","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/?p=11934"},"modified":"2025-09-12T23:09:08","modified_gmt":"2025-09-12T21:09:08","slug":"oferta-de-empleo-para-laboratorio-clinico-y-biomedico-09-09-2025","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/2025\/09\/12\/oferta-de-empleo-para-laboratorio-clinico-y-biomedico-09-09-2025\/","title":{"rendered":"OFERTA DE EMPLEO PARA LABORATORIO CL\u00cdNICO Y BIOM\u00c9DICO (09\/09\/2025)"},"content":{"rendered":"<p>Desde <strong>ALS Madrid<\/strong> se busca un perfil para cubrir un puesto de <strong>asesor t\u00e9cnico comercial<\/strong> para el <strong>departamento de ventas<\/strong>.<\/p>\n<p>Si est\u00e1s interesado y quieres saber todos los detalles, env\u00eda tu CV al siguiente email: <strong>cristinaperez.segura@alsglobal.com<\/strong><\/p>\n<p>La descripci\u00f3n, las funcione y los requisitos del puesto se describen en el siguiente fichero:<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/\/wp-content\/uploads\/ies.benjaminrua.mostoles\/2025\/09\/Info-vacante-asesor-tecnico-comercial-ALS.pdf\">Info vacante asesor t\u00e9cnico comercial ALS<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde ALS Madrid se busca un perfil para cubrir un puesto de asesor t\u00e9cnico comercial para el departamento de ventas. Si est\u00e1s interesado y quieres saber todos los detalles, env\u00eda &#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"post_folder":[],"class_list":["post-11934","post","type-post","status-publish","format-standard","hentry","category-bolsa-de-trabajo"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ies.benjaminrua.mostoles","author_link":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/author\/cuenta_ies-benjaminrua-mostoles\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/category\/bolsa-de-trabajo\/\" rel=\"category tag\">Bolsa de Trabajo<\/a>","rttpg_excerpt":"Desde ALS Madrid se busca un perfil para cubrir un puesto de asesor t\u00e9cnico comercial para el departamento de ventas. Si est\u00e1s interesado y quieres saber todos los detalles, env\u00eda ...","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/posts\/11934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/comments?post=11934"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/posts\/11934\/revisions"}],"predecessor-version":[{"id":11940,"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/posts\/11934\/revisions\/11940"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/media?parent=11934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/categories?post=11934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/tags?post=11934"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/post_folder?post=11934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}