{"id":8458,"date":"2024-02-15T13:51:38","date_gmt":"2024-02-15T12:51:38","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/?p=8458"},"modified":"2024-02-15T13:51:38","modified_gmt":"2024-02-15T12:51:38","slug":"oferta-de-trabajo-para-laborario-clinico-y-biomedico-15-02-2024","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/2024\/02\/15\/oferta-de-trabajo-para-laborario-clinico-y-biomedico-15-02-2024\/","title":{"rendered":"OFERTA DE TRABAJO PARA LABORARIO CL\u00cdNICO Y BIOM\u00c9DICO (15\/02\/2024)"},"content":{"rendered":"<p class=\"v1v1MsoNormal\">Prestigiosa cl\u00ednica privada de Madrid especializada en el Tratamiento de los Trastornos del Sue\u00f1o precisa<\/p>\n<p class=\"v1v1MsoNormal\">t\u00e9cnico superior en an\u00e1lisis cl\u00ednicos<\/p>\n<ul type=\"disc\">\n<li class=\"v1v1MsoListParagraph\">Dedicaci\u00f3n a tiempo parcial<\/li>\n<li class=\"v1v1MsoListParagraph\">remuneraci\u00f3n seg\u00fan experiencia demostrable<\/li>\n<li class=\"v1v1MsoListParagraph\">Se valorar\u00e1 inter\u00e9s en la investigaci\u00f3n cl\u00ednica<\/li>\n<li class=\"v1v1MsoListParagraph\">Localizaci\u00f3n en Madrid-Chamartin<\/li>\n<\/ul>\n<p class=\"v1v1MsoNormal\">Interesados dir\u00edjanse a:<\/p>\n<p class=\"v1v1MsoNormal\"><a href=\"mailto:iis@iis.es\" rel=\"noreferrer\">iis@iis.es<\/a>enviando una carta de presentaci\u00f3n y un CV.<\/p>\n<p class=\"v1v1MsoNormal\"><strong>JUAN DAVID AGUDELO VILLA<\/strong><\/p>\n<p class=\"v1v1MsoNormal\"><strong>\u00a0<\/strong><strong>INSTITUTO DEL SUE\u00d1O<\/strong><\/p>\n<p class=\"v1v1MsoNormal\">Padre Damian, 44. 28036 Madrid (Oficina y Consultas)<\/p>\n<p class=\"v1v1MsoNormal\">Paseo de la Habana, 200 bajo E. 28036 Madrid (Centro de Sue\u00f1o)<\/p>\n<p class=\"v1v1MsoNormal\">Tlf. 91 345 41 29<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prestigiosa cl\u00ednica privada de Madrid especializada en el Tratamiento de los Trastornos del Sue\u00f1o precisa t\u00e9cnico superior en an\u00e1lisis cl\u00ednicos Dedicaci\u00f3n a tiempo parcial remuneraci\u00f3n seg\u00fan experiencia demostrable Se valorar\u00e1 &#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"post_folder":[],"class_list":["post-8458","post","type-post","status-publish","format-standard","hentry","category-bolsa-de-trabajo"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ies.benjaminrua.mostoles","author_link":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/author\/cuenta_ies-benjaminrua-mostoles\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/category\/bolsa-de-trabajo\/\" rel=\"category tag\">Bolsa de Trabajo<\/a>","rttpg_excerpt":"Prestigiosa cl\u00ednica privada de Madrid especializada en el Tratamiento de los Trastornos del Sue\u00f1o precisa t\u00e9cnico superior en an\u00e1lisis cl\u00ednicos Dedicaci\u00f3n a tiempo parcial remuneraci\u00f3n seg\u00fan experiencia demostrable Se valorar\u00e1 ...","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/posts\/8458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/comments?post=8458"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/posts\/8458\/revisions"}],"predecessor-version":[{"id":8459,"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/posts\/8458\/revisions\/8459"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/media?parent=8458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/categories?post=8458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/tags?post=8458"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.benjaminrua.mostoles\/index.php\/wp-json\/wp\/v2\/post_folder?post=8458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}