{"id":5881,"date":"2024-02-09T17:41:51","date_gmt":"2024-02-09T16:41:51","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/?post_type=mec-events&#038;p=5881"},"modified":"2024-02-09T17:41:51","modified_gmt":"2024-02-09T16:41:51","slug":"taller-herramientas-para-la-vida-sesion-3","status":"publish","type":"mec-events","link":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/events\/taller-herramientas-para-la-vida-sesion-3\/","title":{"rendered":"TALLER HERRAMIENTAS PARA LA VIDA. Sesi\u00f3n 3"},"content":{"rendered":"<p>Las habilidades para la vida fueron definidas en 1993 por la Organizaci\u00f3n Mundial de la Salud. Estas habilidades se consideran componentes esenciales de un desarrollo saludable, que favorecen un adecuado afrontamiento de las distintas situaciones que se pueden presentar a lo largo de la vida. En el caso de j\u00f3venes el desarrollo de las habilidades para la vida puede prevenir conductas de riesgo, ense\u00f1ar a controlar la ira, mejorar el desempe\u00f1o acad\u00e9mico y promover el ajuste social positivo. La adquisici\u00f3n de estas habilidades requiere tiempo y algunas suponen un reto para toda la vida.<\/p>\n<p>Se trata de despertar la curiosidad y acercarnos al aprendizaje de forma m\u00e1s l\u00fadica y experiencial contribuyendo as\u00ed al autodescubrimiento y a la adquisici\u00f3n de nuevos recursos haciendo suyas las habilidades desde su propia singularidad.<br \/>\nEs fundamental tambi\u00e9n el papel del grupo como fuente de apoyo, de distintos puntos de vista que favorecen la flexibilidad, en un ambiente distendido, de respeto y aceptaci\u00f3n a todas las aportaciones. De esta forma se convierte en un lugar seguro en el que las y los j\u00f3venes pueden poner a prueba los nuevos recursos adquiridos.<\/p>\n<p>La actividad est\u00e1 dirigida al alumnado de 2\u00ba de CF Grado Superior biling\u00fce y est\u00e1 dentro del Programa de promoci\u00f3n de la salud en el \u00e1mbito educativo del Centro Municipal de Salud comunitaria de Carabanchel.<\/p>\n<p><strong>OBJETIVOS DEL TALLER<\/strong><br \/>\nCon este taller pretendemos:<br \/>\nDesarrollar una actitud m\u00e1s observadora y reflexiva.<\/p>\n<p><strong>CONTENIDOS<\/strong><br \/>\nLas 10 habilidades para la vida son las siguientes:<br \/>\n1. Empat\u00eda<br \/>\n2. Comunicaci\u00f3n asertiva<br \/>\n3. Relaciones interpersonales<br \/>\n4. Toma de decisiones<br \/>\n5. Resoluci\u00f3n de conflictos<br \/>\n6. Pensamiento creativo<br \/>\n7. Pensamiento cr\u00edtico<br \/>\n8. Manejo de emociones y sentimientos<br \/>\n9. Manejo de tensiones y estr\u00e9s<br \/>\n10. Autoconocimiento<br \/>\nEn este Taller de 10 sesiones se van a trabajar de forma equilibrada habilidades relacionadas con la interacci\u00f3n con los dem\u00e1s y habilidades personales m\u00e1s significativas. La duraci\u00f3n de cada sesi\u00f3n ser\u00e1 de hora y media.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las habilidades para la vida fueron definidas en 1993 por la Organizaci\u00f3n Mundial de la Salud. Estas habilidades se consideran componentes esenciales de un desarrollo saludable, que favorecen un adecuado &#8230;<\/p>\n","protected":false},"author":7,"featured_media":5879,"comment_status":"open","ping_status":"closed","template":"","tags":[127],"mec_category":[113],"class_list":["post-5881","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-fp","mec_category-actividad-complementaria"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida.jpg",450,641,false],"landscape":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida.jpg",450,641,false],"portraits":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida.jpg",450,641,false],"thumbnail":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida-211x300.jpg",211,300,true],"large":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida.jpg",450,641,false],"thumblist":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida.jpg",351,500,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida-450x324.jpg",450,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida.jpg",450,641,false],"2048x2048":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida.jpg",450,641,false],"onepress-blog-small":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida-300x150.jpg",300,150,true],"onepress-small":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida-450x300.jpg",450,300,true],"onepress-medium":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida-450x400.jpg",450,400,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida.jpg",334,476,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida.jpg",168,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2024\/02\/taller-herramientas-para-la-vida.jpg",450,641,false]},"rttpg_author":{"display_name":"Gema","author_link":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/author\/gema-mara_parras-serradilla\/"},"rttpg_comment":0,"rttpg_category":" <a href=\"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/tag\/fp\/\" rel=\"tag\">FP<\/a>","rttpg_excerpt":"Las habilidades para la vida fueron definidas en 1993 por la Organizaci\u00f3n Mundial de la Salud. Estas habilidades se consideran componentes esenciales de un desarrollo saludable, que favorecen un adecuado ...","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/mec-events\/5881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=5881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/media\/5879"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=5881"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=5881"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/mec_category?post=5881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}