{"id":2762,"date":"2022-05-05T12:36:24","date_gmt":"2022-05-05T10:36:24","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/?p=2762"},"modified":"2022-05-05T12:36:24","modified_gmt":"2022-05-05T10:36:24","slug":"encuentro-con-la-escritora-monica-rodriguez","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/2022\/05\/05\/encuentro-con-la-escritora-monica-rodriguez\/","title":{"rendered":"Encuentro con la escritora M\u00f3nica Rodr\u00edguez"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2759\" src=\"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2022\/05\/IMG_20220504_130927-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2022\/05\/IMG_20220504_130927-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2022\/05\/IMG_20220504_130927-1024x768.jpg 1024w, https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2022\/05\/IMG_20220504_130927-768x576.jpg 768w, https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2022\/05\/IMG_20220504_130927-1536x1152.jpg 1536w, https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2022\/05\/IMG_20220504_130927-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Nos ha visitado la escritora de novela juvenil M\u00f3nica Rodr\u00edguez.<\/p>\n<p>M\u00f3nica Rodr\u00edguez naci\u00f3 en Oviedo en 1969. Est\u00e1 licenciada en Ciencias F\u00edsicas. En el a\u00f1o 1993 llega a Madrid para hacer un m\u00e1ster de Energ\u00eda Nuclear y desde 1994 hasta el a\u00f1o 2009 estuvo trabajando en el Centro de Investigaciones Energ\u00e9ticas, Medioambientales y Tecnol\u00f3gicas (CIEMAT).<\/p>\n<p>En 2003 public\u00f3 su primer libro infantil y ya en 2009 dej\u00f3 el trabajo en dicho centro para dedicarse por entero a la literatura. Tiene publicados m\u00e1s de una treintena de libros y ha recibido numerosos premios y reconocimientos, como el Ala Delta, el premio Anaya, el premio Alandar y el premio Fundaci\u00f3n Cuatrogatos y ha sido incluida en varias listas de honor.<\/p>\n<p>El acto se ha celebrado en el Sal\u00f3n de Actos para las alumnas y alumnos de 1\u00ba y 2\u00ba de ESO. Aqu\u00ed podemos ver los dos estupendos carteles que ilustran el acto que hemos celebrado:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2760 aligncenter\" src=\"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2022\/05\/IMG_20220504_122839-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2022\/05\/IMG_20220504_122839-225x300.jpg 225w, https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2022\/05\/IMG_20220504_122839-768x1024.jpg 768w, https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2022\/05\/IMG_20220504_122839-300x400.jpg 300w, https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2022\/05\/IMG_20220504_122839-1152x1536.jpg 1152w, https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2022\/05\/IMG_20220504_122839-1536x2048.jpg 1536w, https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2022\/05\/IMG_20220504_122839-scaled.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos ha visitado la escritora de novela juvenil M\u00f3nica Rodr\u00edguez. M\u00f3nica Rodr\u00edguez naci\u00f3 en Oviedo en 1969. Est\u00e1 licenciada en Ciencias F\u00edsicas. En el a\u00f1o 1993 llega a Madrid para &#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-2762","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ENRIQUE NIETO CARRAMI\u00d1ANA","author_link":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/author\/enrique_nieto-carramiana\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"Nos ha visitado la escritora de novela juvenil M\u00f3nica Rodr\u00edguez. M\u00f3nica Rodr\u00edguez naci\u00f3 en Oviedo en 1969. Est\u00e1 licenciada en Ciencias F\u00edsicas. En el a\u00f1o 1993 llega a Madrid para ...","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/posts\/2762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=2762"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/posts\/2762\/revisions"}],"predecessor-version":[{"id":2764,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/posts\/2762\/revisions\/2764"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=2762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/categories?post=2762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=2762"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/post_folder?post=2762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}