{"id":4395,"date":"2023-03-24T16:53:30","date_gmt":"2023-03-24T15:53:30","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/?p=4395"},"modified":"2023-05-25T18:48:53","modified_gmt":"2023-05-25T16:48:53","slug":"visita-a-aula-23","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/2023\/03\/24\/visita-a-aula-23\/","title":{"rendered":"VISITA A AULA 23"},"content":{"rendered":"<p><strong>E<\/strong>l alumnado de Ciclos Formativos de 1\u00ba de Grado Superior ha visitado el jueves, 23 de marzo, Aula 23. La finalidad es que el<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4396 alignleft\" src=\"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-300x225.jpg 300w, https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-1024x768.jpg 1024w, https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-768x576.jpg 768w, https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-1536x1152.jpg 1536w, https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> alumnado conozca ofertas&nbsp; de centros educativos y formativos, entidades y empresas de servicios que dan respuesta a sus necesidades de formaci\u00f3n. Tambi\u00e9n, tienen la posibilidad de acceder a una orientaci\u00f3n educativa que les ayude a analizar las opciones de itinerarios formativos que mejor se adapten a sus inquietudes y posibilidades. Adem\u00e1s, la feria cuenta con distintas propuestas como el Aula de Igualdad, Rob\u00f3tica, Artes esc\u00e9nicas y musicales, Convivencia y Solidaridad. Todo ello para ayudar a los estudiantes a elegir su futuro formativo y profesional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El alumnado de Ciclos Formativos de 1\u00ba de Grado Superior ha visitado el jueves, 23 de marzo, Aula 23. La finalidad es que el alumnado conozca ofertas&nbsp; de centros educativos &#8230;<\/p>\n","protected":false},"author":7,"featured_media":4396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"post_folder":[],"class_list":["post-4395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividad-extraescolar"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-scaled.jpg",2560,1920,false],"landscape":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-scaled.jpg",2560,1920,false],"portraits":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-scaled.jpg",2560,1920,false],"thumbnail":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-300x225.jpg",300,225,true],"large":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-1024x768.jpg",800,600,true],"thumblist":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-scaled.jpg",500,375,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-1536x1152.jpg",1536,1152,true],"2048x2048":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-2048x1536.jpg",2048,1536,true],"onepress-blog-small":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-300x150.jpg",300,150,true],"onepress-small":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-480x300.jpg",480,300,true],"onepress-medium":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-640x400.jpg",640,400,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-scaled.jpg",360,270,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-scaled.jpg",320,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/\/wp-content\/uploads\/ies.calderondelabar.madrid\/2023\/03\/IMG_20230323_165307-scaled.jpg",2560,1920,false]},"rttpg_author":{"display_name":"Gema","author_link":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/author\/gema-mara_parras-serradilla\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/category\/tablon-de-anuncios\/actividad-extraescolar\/\" rel=\"category tag\">Actividad Extraescolar<\/a>","rttpg_excerpt":"El alumnado de Ciclos Formativos de 1\u00ba de Grado Superior ha visitado el jueves, 23 de marzo, Aula 23. La finalidad es que el alumnado conozca ofertas&nbsp; de centros educativos ...","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/posts\/4395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=4395"}],"version-history":[{"count":2,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/posts\/4395\/revisions"}],"predecessor-version":[{"id":4398,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/posts\/4395\/revisions\/4398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/media\/4396"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=4395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/categories?post=4395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=4395"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.calderondelabar.madrid\/index.php\/wp-json\/wp\/v2\/post_folder?post=4395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}