{"id":8475,"date":"2025-05-28T13:49:36","date_gmt":"2025-05-28T11:49:36","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/?p=8475"},"modified":"2025-06-14T19:23:31","modified_gmt":"2025-06-14T17:23:31","slug":"convocatoria-defensa-de-proyecto-de-igualdad-de-genero-del-cfgs-de-promocion-de-igualdad-de-genero","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/2025\/05\/28\/convocatoria-defensa-de-proyecto-de-igualdad-de-genero-del-cfgs-de-promocion-de-igualdad-de-genero\/","title":{"rendered":"Convocatoria defensa de Proyecto de Igualdad de G\u00e9nero del CFGS de Promoci\u00f3n de Igualdad de G\u00e9nero"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8471\" src=\"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-300x169.png\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-300x169.png 300w, https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-1024x576.png 1024w, https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-768x432.png 768w, https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-1536x864.png 1536w, https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1.png 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Se convoca al alumnado matriculado en el m\u00f3dulo profesional de Proyecto de Igualdad de G\u00e9nero del CFGS de Promoci\u00f3n de Igualdad de G\u00e9nero los d\u00edas 12 y 13 de junio a la defensa de los proyectos delante del tribunal conformado para ello (equipo docente).<\/p>\n<p>Las defensas se realizar\u00e1n en el aula 17 del IES.<\/p>\n<p>Se pueden consultar las horas a las que est\u00e1 convocada cada alumna\/o en el aula virtual de Proyecto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se convoca al alumnado matriculado en el m\u00f3dulo profesional de Proyecto de Igualdad de G\u00e9nero del CFGS de Promoci\u00f3n de Igualdad de G\u00e9nero los d\u00edas 12 y 13 de junio a la defensa de los proyectos delante del tribunal conformado para ello (equipo docente). Las defensas se realizar\u00e1n en el aula 17 del IES. Se [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":8471,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,30,107],"tags":[51,31],"post_folder":[],"class_list":["post-8475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cfgs","category-examenes","category-portada","tag-cfgs-promig","tag-examenes"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1.png",1920,1080,false],"landscape":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1.png",1920,1080,false],"portraits":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1.png",1920,1080,false],"thumbnail":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-150x150.png",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-300x169.png",300,169,true],"large":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-1024x576.png",640,360,true],"thumblist":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-300x300.png",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-500x500.png",500,500,true],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-474x324.png",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-391x260.png",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-300x400.png",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-1536x864.png",1536,864,true],"2048x2048":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1.png",1920,1080,false],"total-portfolio-thumb":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-400x400.png",400,400,true],"total-team-thumb":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-350x420.png",350,420,true],"total-blog-thumb":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-400x280.png",400,280,true],"total-thumb":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-100x100.png",100,100,true],"total-blog-header":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-720x360.png",720,360,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-272x182.png",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1.png",360,203,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1.png",360,203,false],"sow-blog-portfolio":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-375x375.png",375,375,true],"sow-blog-grid":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-720x480.png",720,480,true],"sow-blog-alternate":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1-950x630.png",950,630,true],"rt_custom":["https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/\/wp-content\/uploads\/ies.churriguera.leganes\/2025\/05\/Diseno-sin-titulo-1.png",1920,1080,false]},"rttpg_author":{"display_name":"Sergio Jorge Fern\u00e1ndez Ortega","author_link":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/author\/sergio-jorge_fernandez-ortega\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/category\/cfgs\/\" rel=\"category tag\">CFGS<\/a> <a href=\"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/category\/examenes\/\" rel=\"category tag\">Ex\u00e1menes<\/a> <a href=\"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/category\/portada\/\" rel=\"category tag\">Portada<\/a>","rttpg_excerpt":"Se convoca al alumnado matriculado en el m\u00f3dulo profesional de Proyecto de Igualdad de G\u00e9nero del CFGS de Promoci\u00f3n de Igualdad de G\u00e9nero los d\u00edas 12 y 13 de junio a la defensa de los proyectos delante del tribunal conformado para ello (equipo docente). Las defensas se realizar\u00e1n en el aula 17 del IES. Se&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/wp-json\/wp\/v2\/posts\/8475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/wp-json\/wp\/v2\/comments?post=8475"}],"version-history":[{"count":2,"href":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/wp-json\/wp\/v2\/posts\/8475\/revisions"}],"predecessor-version":[{"id":8477,"href":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/wp-json\/wp\/v2\/posts\/8475\/revisions\/8477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/wp-json\/wp\/v2\/media\/8471"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/wp-json\/wp\/v2\/media?parent=8475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/wp-json\/wp\/v2\/categories?post=8475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/wp-json\/wp\/v2\/tags?post=8475"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.churriguera.leganes\/index.php\/wp-json\/wp\/v2\/post_folder?post=8475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}