{"id":1802,"date":"2025-09-23T17:16:54","date_gmt":"2025-09-23T15:16:54","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/?post_type=mec-events&#038;p=1802"},"modified":"2025-09-23T17:16:54","modified_gmt":"2025-09-23T15:16:54","slug":"erasmus-days","status":"publish","type":"mec-events","link":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/events\/erasmus-days\/","title":{"rendered":"Erasmus Days"},"content":{"rendered":"<p>Jornadas informativas del programa Erasmus+ para la comunidad educativa del IES Clara del Rey<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jornadas informativas del programa Erasmus+ para la comunidad educativa del IES Clara del Rey<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","tags":[],"mec_category":[],"class_list":["post-1802","mec-events","type-mec-events","status-publish","hentry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"M.Del Camino Pardo de Vega","author_link":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/author\/m-del-camino_pardo-de-vega\/"},"rttpg_comment":0,"rttpg_category":false,"rttpg_excerpt":"Jornadas informativas del programa Erasmus+ para la comunidad educativa del IES Clara del Rey","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/mec-events\/1802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=1802"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=1802"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=1802"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/mec_category?post=1802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}