{"id":1367,"date":"2025-08-28T18:32:33","date_gmt":"2025-08-28T16:32:33","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/?page_id=1367"},"modified":"2025-08-28T18:33:28","modified_gmt":"2025-08-28T16:33:28","slug":"colaborar-en-la-fp-dual","status":"publish","type":"page","link":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/colaborar-en-la-fp-dual\/","title":{"rendered":"Colaborar en la FP Dual"},"content":{"rendered":"\n<p>Si representa a una empresa y est\u00e1 interesado, p\u00f3ngase inmediatamente en contacto:<strong>\u00a0<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\"><a href=\"mailto:empresas@iesclaradelrey.es\">empresas@iesclaradelrey.e<\/a>s<\/mark><\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si representa a una empresa y est\u00e1 interesado, p\u00f3ngase inmediatamente en contacto:\u00a0empresas@iesclaradelrey.es<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"folder":[],"class_list":["post-1367","page","type-page","status-publish","hentry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ies.claradelrey.madrid","author_link":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/author\/cuenta_ies-claradelrey-madrid\/"},"rttpg_comment":0,"rttpg_category":false,"rttpg_excerpt":"Si representa a una empresa y est\u00e1 interesado, p\u00f3ngase inmediatamente en contacto:\u00a0empresas@iesclaradelrey.es","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/pages\/1367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=1367"}],"version-history":[{"count":2,"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/pages\/1367\/revisions"}],"predecessor-version":[{"id":1369,"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/pages\/1367\/revisions\/1369"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=1367"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.claradelrey.madrid\/index.php\/wp-json\/wp\/v2\/folder?post=1367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}