{"id":10042,"date":"2025-03-07T19:47:28","date_gmt":"2025-03-07T18:47:28","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/?p=10042"},"modified":"2025-03-07T20:09:54","modified_gmt":"2025-03-07T19:09:54","slug":"dia-internacional-de-la-mujer-el-infanta-se-viste-de-morado","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/novedades\/dia-internacional-de-la-mujer-el-infanta-se-viste-de-morado\/","title":{"rendered":"D\u00eda Internacional de la Mujer: El Infanta se viste de morado"},"content":{"rendered":"<div id=\"pl-10042\"  class=\"panel-layout\" ><div id=\"pg-10042-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-10042-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-10042-0-0-0\" class=\"so-panel widget widget_text panel-first-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><p>La comunidad educativa del IES Infanta Elena se suma a la celebraci\u00f3n del D\u00eda Internacional de la Mujer con el lema<\/p>\n<div id=\"v1forwardbody1\">\n<div><\/div>\n<div><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0EL INFANTA SE VISTE DE MORADO<\/strong><\/div>\n<div><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/strong><\/div>\n<div><\/div>\n<div>El 10 de marzo nos haremos ver \u00abde morado\u00bb.<\/div>\n<\/div>\n<\/div>\n\t\t<\/div><div id=\"panel-10042-0-0-1\" class=\"so-panel widget widget_sow-headline panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-headline so-widget-sow-headline-default-7e44911586ab-10042\"\n\t\t\t\n\t\t><div class=\"sow-headline-container \">\n\t\t\t\t\t\t<div class=\"decoration\">\n\t\t\t\t\t\t<div class=\"decoration-inside\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-10042-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-10042-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-10042-1-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-10042\"\n\t\t\t\n\t\t>\n\n<div class=\"sow-image-container\">\n\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/cartel_dia_mujer_marzo.jpg\" width=\"1447\" height=\"2048\" srcset=\"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/cartel_dia_mujer_marzo.jpg 1447w, https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/cartel_dia_mujer_marzo-212x300.jpg 212w, https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/cartel_dia_mujer_marzo-724x1024.jpg 724w, https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/cartel_dia_mujer_marzo-768x1087.jpg 768w, https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/cartel_dia_mujer_marzo-1085x1536.jpg 1085w\" sizes=\"auto, (max-width: 1447px) 100vw, 1447px\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>La comunidad educativa del IES Infanta Elena se suma a la celebraci\u00f3n del D\u00eda Internacional de la Mujer con el lema \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0EL INFANTA SE VISTE DE MORADO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 El 10 de marzo nos haremos [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":10050,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"post_folder":[],"class_list":["post-10042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025.png",1000,800,false],"landscape":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025.png",1000,800,false],"portraits":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025.png",1000,800,false],"thumbnail":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025-150x150.png",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025-300x240.png",300,240,true],"large":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025.png",525,420,false],"thumblist":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025-300x300.png",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025-500x500.png",500,500,true],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025-474x324.png",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025-391x260.png",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025-300x400.png",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025.png",1000,800,false],"2048x2048":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025.png",1000,800,false],"gurukul-education-featured-image":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025.png",1000,800,false],"gurukul-education-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025-100x100.png",100,100,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025-272x182.png",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025.png",360,288,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025.png",300,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/03\/Dia-Internacional-de-la-Mujer-2025.png",1000,800,false]},"rttpg_author":{"display_name":"Avelino Bern\u00e1rdez Portas","author_link":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/author\/avelino_bernrdez-portas\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/category\/novedades\/\" rel=\"category tag\">Novedades<\/a>","rttpg_excerpt":"La comunidad educativa del IES Infanta Elena se suma a la celebraci\u00f3n del D\u00eda Internacional de la Mujer con el lema \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0EL INFANTA SE VISTE DE MORADO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 El 10 de marzo nos haremos&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/10042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/comments?post=10042"}],"version-history":[{"count":2,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/10042\/revisions"}],"predecessor-version":[{"id":10045,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/10042\/revisions\/10045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/media\/10050"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/media?parent=10042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/categories?post=10042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/tags?post=10042"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/post_folder?post=10042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}