{"id":10685,"date":"2025-12-03T18:37:39","date_gmt":"2025-12-03T17:37:39","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/?p=10685"},"modified":"2025-12-03T19:42:32","modified_gmt":"2025-12-03T18:42:32","slug":"reunion-informativa-sobre-programa-de-acogida-de-estudiantes-japoneses","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/novedades\/reunion-informativa-sobre-programa-de-acogida-de-estudiantes-japoneses\/","title":{"rendered":"Reuni\u00f3n informativa sobre Programa de acogida de estudiantes japoneses"},"content":{"rendered":"<div id=\"pl-10685\"  class=\"panel-layout\" ><div id=\"pg-10685-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-10685-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-10685-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><p>Con el fin de cerrar el grupo de familias acogedoras de estudiantes japoneses, de las cuales nos faltan todav\u00eda dos (de un total de 15), os animamos a asistir a una charla informativa sobre el programa de acogida de estudiantes japoneses para que pod\u00e1is comprobar de primera mano la bonita y enriquecedora experiencia con la que llevamos ya varios a\u00f1os disfrutando.<\/p>\n<p>La fecha de esta reuni\u00f3n informativa es el <strong>mi\u00e9rcoles, 10 de diciembre, a las 17:00 horas, en el aula ATECA <\/strong>del IES Infanta Elena.<\/p>\n<p>Os recordamos la informaci\u00f3n general sobre este programa cultural:<\/p>\n<p>Se trata de un grupo de <strong>15 estudiantes japoneses, procedentes del Zama Sogo Hiagh School, de Kanagawa, de edades comprendidas entre 15 y 17 a\u00f1os, con dos profesores<\/strong>, cuyas fechas de estancia en Galapagar ser\u00e1n <strong>del 19 al 27 de marzo de 2026<\/strong>.<\/p>\n<p>El programa de acogida conlleva una dotaci\u00f3n econ\u00f3mica diaria de unos 25 euros diarios.<\/p>\n<p>La idea de este programa es la de integrarse en la cultura y costumbres espa\u00f1olas, con una planificaci\u00f3n de actividades diarias ya organizadas, que pasa por la asistencia a clases (en el Infanta Elena) a diferentes actividades complementarias y extraescolares, que os comentaremos el d\u00eda de la reuni\u00f3n.<\/p>\n<p>En el caso de estar interesados (aunque, todav\u00eda sin compromiso), os rogamos que <strong>escrib\u00e1is a la direcci\u00f3n de correo del Director<\/strong>, Avelino Bern\u00e1rdez, (a <a href=\"mailto:avelino.bernardez@educa.madrid.org\">avelino.bernardez@educa.madrid.org<\/a>), confirmando el inter\u00e9s por este programa de acogida o bien, present\u00e1ndoos el d\u00eda de la reuni\u00f3n.<\/p>\n<p>\u00a1No dud\u00e9is en participar de esta maravillosa experiencia!<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Con el fin de cerrar el grupo de familias acogedoras de estudiantes japoneses, de las cuales nos faltan todav\u00eda dos (de un total de 15), os animamos a asistir a una charla informativa sobre el programa de acogida de estudiantes japoneses para que pod\u00e1is comprobar de primera mano la bonita y enriquecedora experiencia con la [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":10690,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"post_folder":[],"class_list":["post-10685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1.png",1123,794,false],"landscape":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1.png",1123,794,false],"portraits":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1.png",1123,794,false],"thumbnail":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1-150x150.png",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1-300x212.png",300,212,true],"large":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1-1024x724.png",525,371,true],"thumblist":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1-300x300.png",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1-500x500.png",500,500,true],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1-474x324.png",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1-391x260.png",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1-300x400.png",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1.png",1123,794,false],"2048x2048":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1.png",1123,794,false],"gurukul-education-featured-image":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1.png",1123,794,false],"gurukul-education-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1-100x100.png",100,100,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1-272x182.png",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1-360x476.png",360,476,true],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1-360x240.png",360,240,true],"rt_custom":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2025\/12\/Cartel-Acogida-Japoneses-1.png",1123,794,false]},"rttpg_author":{"display_name":"Avelino Bern\u00e1rdez Portas","author_link":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/author\/avelino_bernrdez-portas\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/category\/novedades\/\" rel=\"category tag\">Novedades<\/a>","rttpg_excerpt":"Con el fin de cerrar el grupo de familias acogedoras de estudiantes japoneses, de las cuales nos faltan todav\u00eda dos (de un total de 15), os animamos a asistir a una charla informativa sobre el programa de acogida de estudiantes japoneses para que pod\u00e1is comprobar de primera mano la bonita y enriquecedora experiencia con la&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/10685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/comments?post=10685"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/10685\/revisions"}],"predecessor-version":[{"id":10687,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/10685\/revisions\/10687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/media\/10690"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/media?parent=10685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/categories?post=10685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/tags?post=10685"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/post_folder?post=10685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}