{"id":4249,"date":"2022-02-10T21:52:07","date_gmt":"2022-02-10T20:52:07","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/?p=4249"},"modified":"2022-02-10T21:53:34","modified_gmt":"2022-02-10T20:53:34","slug":"modificacion-del-uso-de-mascarillas-orden-168-2022","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/novedades\/modificacion-del-uso-de-mascarillas-orden-168-2022\/","title":{"rendered":"Modificaci\u00f3n del uso de mascarillas (Orden 168\/2022)"},"content":{"rendered":"<p>En la Orden 168\/2022 <em>de Consejer\u00eda de Sanidad de fecha 10 de febrero de 2022<\/em>&nbsp;se determina que, en los centros docentes que ofrezcan las ense\u00f1anzas recogidas en el art\u00edculo 3 de la LOE 2\/2006 de 3 de mayo de educaci\u00f3n,&nbsp;<strong>no ser\u00e1 exigible el uso de mascarillas durante los periodos de recreo y en el desarrollo de otras actividades siempre que se realicen, en ambos casos, en espacios al aire libre<\/strong>.<\/p>\n<p>Recomendamos, en cualquier caso, al alumnado prudencia e, independientemente de que no sea obligatorio, que se siga utilizando la mascarilla cuando no se pueda respetar la distancia interpersonal marcada en la normativa. En este punto, queremos transmitir la preocupaci\u00f3n y la necesidad de extremar el cuidado en la salida y entrada del centro, as\u00ed como a la hora de comprar en la cafeter\u00eda.<\/p>\n<p>Recordamos que dentro del edificio se debe mantener el uso de las mascarillas como hasta ahora.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la Orden 168\/2022 de Consejer\u00eda de Sanidad de fecha 10 de febrero de 2022&nbsp;se determina que, en los centros docentes que ofrezcan las ense\u00f1anzas recogidas en el art\u00edculo 3 de la LOE 2\/2006 de 3 de mayo de educaci\u00f3n,&nbsp;no ser\u00e1 exigible el uso de mascarillas durante los periodos de recreo y en el desarrollo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4253,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"post_folder":[],"class_list":["post-4249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false],"landscape":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false],"portraits":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false],"thumbnail":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false],"large":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false],"thumblist":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false],"thumbrelated":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false],"gridsquare":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false],"tileview":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false],"1536x1536":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false],"2048x2048":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false],"gurukul-education-featured-image":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false],"gurukul-education-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",100,100,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1-250x182.jpg",250,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",239,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/Sin-titulo-1.jpg",250,251,false]},"rttpg_author":{"display_name":"Cuenta","author_link":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/author\/cuenta_ies-infantaelena-galapagar\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/category\/novedades\/\" rel=\"category tag\">Novedades<\/a>","rttpg_excerpt":"En la Orden 168\/2022 de Consejer\u00eda de Sanidad de fecha 10 de febrero de 2022&nbsp;se determina que, en los centros docentes que ofrezcan las ense\u00f1anzas recogidas en el art\u00edculo 3 de la LOE 2\/2006 de 3 de mayo de educaci\u00f3n,&nbsp;no ser\u00e1 exigible el uso de mascarillas durante los periodos de recreo y en el desarrollo&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/4249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/comments?post=4249"}],"version-history":[{"count":3,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/4249\/revisions"}],"predecessor-version":[{"id":4254,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/4249\/revisions\/4254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/media\/4253"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/media?parent=4249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/categories?post=4249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/tags?post=4249"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/post_folder?post=4249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}