{"id":4356,"date":"2022-03-18T13:50:00","date_gmt":"2022-03-18T12:50:00","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/?p=4356"},"modified":"2022-03-19T10:42:05","modified_gmt":"2022-03-19T09:42:05","slug":"jornada-de-puertas-abiertas-2021-2022-21-de-marzo-a-las-1730-horas","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/novedades\/jornada-de-puertas-abiertas-2021-2022-21-de-marzo-a-las-1730-horas\/","title":{"rendered":"Jornada de Puertas Abiertas:                           21 de marzo, a las 17:30 horas"},"content":{"rendered":"<p>Estimadas familias:<\/p>\n<p>A finales de este curso, vuestros\/as hijos\/as concluyen la etapa de Ense\u00f1anza Primaria,<br \/>\ny se preparan para iniciar sus estudios de Ense\u00f1anza Secundaria en el curso 2022\/23.<br \/>\nEn este sentido, somos conscientes de la importancia que conlleva dicho cambio, tanto<br \/>\nen lo educativo como en lo personal.<\/p>\n<p>El IES Infanta Elena lleva 30 a\u00f1os ofreciendo al alumnado de Galapagar una amplia<br \/>\noferta educativa con un claustro de profesores comprometidos con la comunidad<br \/>\neducativa a trav\u00e9s de sus diferentes planes y proyectos.<br \/>\nPara ello, nos gustar\u00eda poder contar con vuestra presencia en nuestra Jornada de<br \/>\nPuertas Abiertas, que tendr\u00e1 lugar el 21 de marzo a las 17h30, en el Sal\u00f3n de Usos<br \/>\nM\u00faltiples del centro.<\/p>\n<p>Tanto el equipo directivo como una representaci\u00f3n del claustro del IES infanta Elena<br \/>\nestaremos encantados de recibiros e informaros de todo lo que concierne a la<br \/>\ncomunidad educativa del IES Infanta Elena.<\/p>\n<p>Sin m\u00e1s, os emplazamos a esta cita, esperando que dicha presentaci\u00f3n cumpla las<br \/>\nexpectativas que vosotros y vuestros\/as hijos\/as requieren para acometer una nueva<br \/>\netapa educativa en el instituto.<\/p>\n<p>EL EQUIPO DIRECTIVO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias: A finales de este curso, vuestros\/as hijos\/as concluyen la etapa de Ense\u00f1anza Primaria, y se preparan para iniciar sus estudios de Ense\u00f1anza Secundaria en el curso 2022\/23. En este sentido, somos conscientes de la importancia que conlleva dicho cambio, tanto en lo educativo como en lo personal. El IES Infanta Elena lleva 30 [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":4361,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"post_folder":[],"class_list":["post-4356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"landscape":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"portraits":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"thumbnail":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"large":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"thumblist":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"thumbrelated":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"gridsquare":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"tileview":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"1536x1536":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"2048x2048":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"gurukul-education-featured-image":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"gurukul-education-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",100,58,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-272x173.jpg",272,173,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false],"rt_custom":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/02\/jornada_puertas_abiertas_logo3-e1645707472267.jpg",200,116,false]},"rttpg_author":{"display_name":"Avelino Bern\u00e1rdez Portas","author_link":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/author\/avelino_bernrdez-portas\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/category\/novedades\/\" rel=\"category tag\">Novedades<\/a>","rttpg_excerpt":"Estimadas familias: A finales de este curso, vuestros\/as hijos\/as concluyen la etapa de Ense\u00f1anza Primaria, y se preparan para iniciar sus estudios de Ense\u00f1anza Secundaria en el curso 2022\/23. En este sentido, somos conscientes de la importancia que conlleva dicho cambio, tanto en lo educativo como en lo personal. El IES Infanta Elena lleva 30&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/4356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/comments?post=4356"}],"version-history":[{"count":3,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/4356\/revisions"}],"predecessor-version":[{"id":4363,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/4356\/revisions\/4363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/media\/4361"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/media?parent=4356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/categories?post=4356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/tags?post=4356"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/post_folder?post=4356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}