{"id":5695,"date":"2022-10-26T20:32:24","date_gmt":"2022-10-26T18:32:24","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/?p=5695"},"modified":"2022-10-28T21:22:47","modified_gmt":"2022-10-28T19:22:47","slug":"5695","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/novedades\/5695\/","title":{"rendered":"Celebrando la Semana de Difuntos o de Muertos: del 24 al 28 de octubre"},"content":{"rendered":"\n<p><\/p>\n\n\n<p>La semana del 24 al 28 de octubre se celebrar\u00e1 en el IES infanta Elena La Semana de los Difuntos o Halloween. Diferentes departamentos realizar\u00e1n actividades relacionadas con esta festividad.<\/p>\n<ul>\n<li><strong>Concurso de Galer\u00eda de monstruos para 1\u00ba de ESO<\/strong><\/li>\n<li><strong>Concurso de Leyendas urbanas para 2\u00ba de ESO<\/strong><\/li>\n<li><strong>Para el alumnado de 3\u00ba de ESO, Concurso de Microrrelatos de terror<\/strong><\/li>\n<li><strong>Para el alumnado de 4\u00ba de la ESO, Concurso de Leyendas de terror<\/strong><\/li>\n<li><strong>Concurso de disfraces para alumnos y profesores (TESEAS).<\/strong>&nbsp;Pueden optar al premio de forma individual o por grupos.&nbsp; En el vest\u00edbulo habr\u00e1 un photocall para los interesados en participar. El jurado estar\u00e1 compuesto por alumnos de grado superior y profesores del Centro. Se valorar\u00e1 la originalidad en la tem\u00e1tica Halloween, la creatividad (si el disfraz no es comprado) y&nbsp; la realizaci\u00f3n de alguna peque\u00f1a representaci\u00f3n. En el recreo se entregar\u00e1n los premios en el Aula de usos m\u00faltiples.<\/li>\n<\/ul>\n<ul>\n<li><strong>Venta ben\u00e9fica de chuches (IAEE)<\/strong>.<\/li>\n<\/ul>\n<ul>\n<li><strong>1\u00aa y 2\u00aa horas (para 2\u00ba de la ESO).<\/strong>&nbsp;Din\u00e1micas en aula y pistas (TESEAS)<\/li>\n<li><strong>3\u00aa y 4\u00aa horas (para 3\u00ba de la ESO).<\/strong>&nbsp;Din\u00e1micas en aula y pistas (TESEAS) y Pases de cortos de miedo (IAEE)<\/li>\n<\/ul>\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/mediateca.educa.madrid.org\/video\/88stc43gzr94pldq\/fs\" width=\"650\" height=\"470\" frameborder=\"0\" scrolling=\"no\" style=\"border:0;overflow:hidden\" allowfullscreen><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>La semana del 24 al 28 de octubre se celebrar\u00e1 en el IES infanta Elena La Semana de los Difuntos o Halloween. Diferentes departamentos realizar\u00e1n actividades relacionadas con esta festividad. Concurso de Galer\u00eda de monstruos para 1\u00ba de ESO Concurso de Leyendas urbanas para 2\u00ba de ESO Para el alumnado de 3\u00ba de ESO, Concurso [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5696,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"post_folder":[],"class_list":["post-5695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN.jpg",339,277,false],"landscape":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN.jpg",339,277,false],"portraits":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN.jpg",339,277,false],"thumbnail":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN-300x245.jpg",300,245,true],"large":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN.jpg",339,277,false],"thumblist":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN-300x277.jpg",300,277,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN.jpg",339,277,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN.jpg",339,277,false],"gridsquare":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN-339x260.jpg",339,260,true],"tileview":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN-300x277.jpg",300,277,true],"1536x1536":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN.jpg",339,277,false],"2048x2048":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN.jpg",339,277,false],"gurukul-education-featured-image":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN.jpg",339,277,false],"gurukul-education-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN.jpg",100,82,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN.jpg",339,277,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN.jpg",294,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2022\/10\/HALLOWEEN.jpg",339,277,false]},"rttpg_author":{"display_name":"Cuenta","author_link":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/author\/cuenta_ies-infantaelena-galapagar\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/category\/novedades\/\" rel=\"category tag\">Novedades<\/a>","rttpg_excerpt":"La semana del 24 al 28 de octubre se celebrar\u00e1 en el IES infanta Elena La Semana de los Difuntos o Halloween. Diferentes departamentos realizar\u00e1n actividades relacionadas con esta festividad. Concurso de Galer\u00eda de monstruos para 1\u00ba de ESO Concurso de Leyendas urbanas para 2\u00ba de ESO Para el alumnado de 3\u00ba de ESO, Concurso&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/5695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/comments?post=5695"}],"version-history":[{"count":7,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/5695\/revisions"}],"predecessor-version":[{"id":5709,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/5695\/revisions\/5709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/media\/5696"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/media?parent=5695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/categories?post=5695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/tags?post=5695"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/post_folder?post=5695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}