{"id":6371,"date":"2023-02-17T18:55:06","date_gmt":"2023-02-17T17:55:06","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/?p=6371"},"modified":"2023-02-21T21:11:15","modified_gmt":"2023-02-21T20:11:15","slug":"celebramos-el-carnaval-en-1o-de-eso","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/novedades\/celebramos-el-carnaval-en-1o-de-eso\/","title":{"rendered":"Celebramos el Carnaval en 1\u00ba de ESO: lunes, 20 de febrero"},"content":{"rendered":"<div id=\"pl-6371\"  class=\"panel-layout\" ><div id=\"pg-6371-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-6371-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-6371-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t<div class=\"textwidget\"><p>El lunes 20 de febrero, el alumnado de 1\u00ba ESO\u00a0 va a celebrar el CARNAVAL durante las tres primeras horas de la ma\u00f1ana junto con sus tutores y profesores.<\/p>\n<p>Esta celebraci\u00f3n la llevar\u00e1n a cabo junto con los alumnos del grado superior de Actividades F\u00edsico-Deportivas (TESEAS).<\/p>\n<p>La tem\u00e1tica para carnaval ser\u00e1 la misma que la de los proyectos de 1\u00ba ESO: Am\u00e9rica<\/p>\n<p>\u00a1Animamos a todos a disfrazarse! Habr\u00e1 una larga lista de premios para la clase que tenga los mejores disfraces.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><div id=\"pg-6371-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-6371-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-6371-1-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-headline so-widget-sow-headline-default-d6b5de2c6e5c-6371\"\n\t\t\t\n\t\t><div class=\"sow-headline-container \">\n\t\t\t\t\t\t<div class=\"decoration\">\n\t\t\t\t\t\t<div class=\"decoration-inside\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-6371-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-6371-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-6371-2-0-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"2\" ><img loading=\"lazy\" decoding=\"async\" width=\"258\" height=\"300\" src=\"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces-258x300.jpg\" class=\"image wp-image-6372  attachment-medium size-medium\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces-258x300.jpg 258w, https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces.jpg 737w\" sizes=\"auto, (max-width: 258px) 100vw, 258px\" \/><\/div><\/div><div id=\"pgc-6371-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-6371-2-1-0\" class=\"widget_text so-panel widget widget_custom_html panel-first-child panel-last-child\" data-index=\"3\" ><div class=\"textwidget custom-html-widget\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/gRI6Zqdxqe8\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>El lunes 20 de febrero, el alumnado de 1\u00ba ESO\u00a0 va a celebrar el CARNAVAL durante las tres primeras horas de la ma\u00f1ana junto con sus tutores y profesores. Esta celebraci\u00f3n la llevar\u00e1n a cabo junto con los alumnos del grado superior de Actividades F\u00edsico-Deportivas (TESEAS). La tem\u00e1tica para carnaval ser\u00e1 la misma que la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6374,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"post_folder":[],"class_list":["post-6371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2.jpg",601,573,false],"landscape":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2.jpg",601,573,false],"portraits":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2.jpg",601,573,false],"thumbnail":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2-300x286.jpg",300,286,true],"large":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2.jpg",525,501,false],"thumblist":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2.jpg",500,477,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2.jpg",601,573,false],"2048x2048":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2.jpg",601,573,false],"gurukul-education-featured-image":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2.jpg",601,573,false],"gurukul-education-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2.jpg",100,95,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2.jpg",360,343,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2.jpg",252,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/02\/disfraces2.jpg",601,573,false]},"rttpg_author":{"display_name":"Cuenta","author_link":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/author\/cuenta_ies-infantaelena-galapagar\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/category\/novedades\/\" rel=\"category tag\">Novedades<\/a>","rttpg_excerpt":"El lunes 20 de febrero, el alumnado de 1\u00ba ESO\u00a0 va a celebrar el CARNAVAL durante las tres primeras horas de la ma\u00f1ana junto con sus tutores y profesores. Esta celebraci\u00f3n la llevar\u00e1n a cabo junto con los alumnos del grado superior de Actividades F\u00edsico-Deportivas (TESEAS). La tem\u00e1tica para carnaval ser\u00e1 la misma que la&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/6371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/comments?post=6371"}],"version-history":[{"count":10,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/6371\/revisions"}],"predecessor-version":[{"id":6384,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/6371\/revisions\/6384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/media\/6374"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/media?parent=6371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/categories?post=6371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/tags?post=6371"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/post_folder?post=6371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}