{"id":8479,"date":"2023-12-14T18:32:49","date_gmt":"2023-12-14T17:32:49","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/?p=8479"},"modified":"2023-12-14T18:39:00","modified_gmt":"2023-12-14T17:39:00","slug":"borrador","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/novedades\/borrador\/","title":{"rendered":"Taller Retos juveniles para familias\/profesorado"},"content":{"rendered":"<div id=\"pl-8479\"  class=\"panel-layout\" ><div id=\"pg-8479-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-8479-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-8479-0-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"0\" ><h3 class=\"widget-title\">Taller Retos juveniles para familias\/profesorado (m\u00f3viles, redes sociales&#8230;)<\/h3>\t\t\t<div class=\"textwidget\"><p>A toda la comunidad educativa de Galapagar:<\/p>\n<p>Con esta circular queremos invitar a las familias interesadas a una charla-coloquio sobre <strong>los retos a los que se enfrentan todas las familias, profesorado y entorno social<\/strong> (Redes sociales, m\u00f3viles, comportamientos disruptivos\u2026) a trav\u00e9s de una mesa redonda abierta en la que participar\u00e1n diferentes sectores de las familias, servicios sociales, profesorado, agentes del Plan Director (Guardia Civil), coach especializada en menores, personal especializada en derecho jur\u00eddico (abogado).<\/p>\n<p>Para ello, os emplazamos a esta charla amena que se realizar\u00e1 en el sal\u00f3n de usos m\u00faltiples del IES Infanta Elena, el <strong>21 de diciembre, a las 18:00 horas<\/strong>.<\/p>\n<p>La entrada ser\u00e1 libre hasta completar aforo.<\/p>\n<p>Sin m\u00e1s, esperando contar con vuestra presencia y participaci\u00f3n, recibid un cordial saludo.<\/p>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A toda la comunidad educativa de Galapagar: Con esta circular queremos invitar a las familias interesadas a una charla-coloquio sobre los retos a los que se enfrentan todas las familias, profesorado y entorno social (Redes sociales, m\u00f3viles, comportamientos disruptivos\u2026) a trav\u00e9s de una mesa redonda abierta en la que participar\u00e1n diferentes sectores de las familias, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8487,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"post_folder":[],"class_list":["post-8479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233.jpg",560,350,false],"landscape":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233.jpg",560,350,false],"portraits":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233.jpg",560,350,false],"thumbnail":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233-300x188.jpg",300,188,true],"large":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233.jpg",525,328,false],"thumblist":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233.jpg",500,313,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233-300x350.jpg",300,350,true],"1536x1536":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233.jpg",560,350,false],"2048x2048":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233.jpg",560,350,false],"gurukul-education-featured-image":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233.jpg",560,350,false],"gurukul-education-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233.jpg",100,63,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233.jpg",360,225,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233.jpg",360,225,false],"rt_custom":["https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/\/wp-content\/uploads\/ies.infantaelena.galapagar\/2023\/12\/CARTEL_TALLER_MOVIL_233.jpg",560,350,false]},"rttpg_author":{"display_name":"Cuenta","author_link":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/author\/cuenta_ies-infantaelena-galapagar\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/category\/novedades\/\" rel=\"category tag\">Novedades<\/a>","rttpg_excerpt":"A toda la comunidad educativa de Galapagar: Con esta circular queremos invitar a las familias interesadas a una charla-coloquio sobre los retos a los que se enfrentan todas las familias, profesorado y entorno social (Redes sociales, m\u00f3viles, comportamientos disruptivos\u2026) a trav\u00e9s de una mesa redonda abierta en la que participar\u00e1n diferentes sectores de las familias,&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/8479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/comments?post=8479"}],"version-history":[{"count":6,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/8479\/revisions"}],"predecessor-version":[{"id":8489,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/posts\/8479\/revisions\/8489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/media\/8487"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/media?parent=8479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/categories?post=8479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/tags?post=8479"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.infantaelena.galapagar\/wp-json\/wp\/v2\/post_folder?post=8479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}