{"id":4033,"date":"2021-04-07T09:31:38","date_gmt":"2021-04-07T09:31:38","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/?p=4033"},"modified":"2021-04-07T09:32:06","modified_gmt":"2021-04-07T09:32:06","slug":"proceso-admision-plazas-vacantes-ofertadas-eso-y-bachillerato","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/2021\/04\/07\/proceso-admision-plazas-vacantes-ofertadas-eso-y-bachillerato\/","title":{"rendered":"PROCESO ADMISI\u00d3N 2021-22: PLAZAS VACANTES OFERTADAS ESO Y BACHILLERATO"},"content":{"rendered":"\n<div class=\"wp-block-file\"><a href=\"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/\/wp-content\/uploads\/ies.lapoveda.arganda\/2021\/04\/Anexo_I._Plazas_vacantes_ofertadas_Publicable.pdf\">Anexo I. Plazas vacantes ofertadas<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"post_folder":[],"class_list":["post-4033","post","type-post","status-publish","format-standard","hentry","category-tablon-general"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ies.lapoveda.arganda","author_link":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/author\/cuenta_ies-lapoveda-arganda\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/category\/tablon-general\/\" rel=\"category tag\">General IES La Poveda<\/a>","rttpg_excerpt":null,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/posts\/4033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/comments?post=4033"}],"version-history":[{"count":3,"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/posts\/4033\/revisions"}],"predecessor-version":[{"id":4037,"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/posts\/4033\/revisions\/4037"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/media?parent=4033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/categories?post=4033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/tags?post=4033"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/post_folder?post=4033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}