{"id":4648,"date":"2022-01-14T13:54:27","date_gmt":"2022-01-14T12:54:27","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/?p=4648"},"modified":"2022-01-17T11:29:49","modified_gmt":"2022-01-17T10:29:49","slug":"viaje-ski-andorra-reunion-con-familias-de-alumnos-participantes","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/2022\/01\/14\/viaje-ski-andorra-reunion-con-familias-de-alumnos-participantes\/","title":{"rendered":"Viaje Ski Andorra: reuni\u00f3n con familias de alumnos participantes."},"content":{"rendered":"<p>La reuni\u00f3n comenzar\u00e1 a las 16:00. Para participar en ella deben conectarse a trav\u00e9s del siguiente enlace:<\/p>\n<p>REUNI\u00d3N FAMILIAS SKI<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La reuni\u00f3n comenzar\u00e1 a las 16:00. Para participar en ella deben conectarse a trav\u00e9s del siguiente enlace: REUNI\u00d3N FAMILIAS SKI<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"post_folder":[],"class_list":["post-4648","post","type-post","status-publish","format-standard","hentry","category-tablon-general"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ies.lapoveda.arganda","author_link":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/author\/cuenta_ies-lapoveda-arganda\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/category\/tablon-general\/\" rel=\"category tag\">General IES La Poveda<\/a>","rttpg_excerpt":"La reuni\u00f3n comenzar\u00e1 a las 16:00. Para participar en ella deben conectarse a trav\u00e9s del siguiente enlace: REUNI\u00d3N FAMILIAS SKI","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/posts\/4648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/comments?post=4648"}],"version-history":[{"count":4,"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/posts\/4648\/revisions"}],"predecessor-version":[{"id":4652,"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/posts\/4648\/revisions\/4652"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/media?parent=4648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/categories?post=4648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/tags?post=4648"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lapoveda.arganda\/index.php\/wp-json\/wp\/v2\/post_folder?post=4648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}