{"id":2619,"date":"2024-01-08T18:01:42","date_gmt":"2024-01-08T17:01:42","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/?p=2619"},"modified":"2024-01-10T18:34:32","modified_gmt":"2024-01-10T17:34:32","slug":"ii-jornada-de-emprendimiento","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/2024\/01\/08\/ii-jornada-de-emprendimiento\/","title":{"rendered":"II JORNADA DE EMPRENDIMIENTO"},"content":{"rendered":"\n<p><span style=\"color: #000000;\"><br><\/span><span style=\"color: #000000;\">El 18 de enero, el alumnado de nuestros Grados Superiores tiene una cita en la APE del centro con antiguos alumnos y emprendedores locales, en la II Jornada de Emprendimiento del IES Las Encinas.<\/span><\/p>\n\n\n\n<p><span style=\"color: #000000;\">\u00bfQuieres saber qui\u00e9nes participar\u00e1n en el evento? Pincha para ver el <a href=\"https:\/\/drive.google.com\/file\/d\/1SK-if7vk-vN_xZdsAtxvzkfP9QRT1L2D\/view?usp=sharing\"><strong>CARTEL INFORMATIVO.<\/strong><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 18 de enero, el alumnado de nuestros Grados Superiores tiene una cita en la APE del centro con antiguos alumnos y emprendedores locales, en la II Jornada de Emprendimiento &#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-2619","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ies.lasencinas.villanuevadelacanada","author_link":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/author\/cuenta_ies-lasencinas-villanuevadelacanada\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"El 18 de enero, el alumnado de nuestros Grados Superiores tiene una cita en la APE del centro con antiguos alumnos y emprendedores locales, en la II Jornada de Emprendimiento ...","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/posts\/2619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/comments?post=2619"}],"version-history":[{"count":5,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/posts\/2619\/revisions"}],"predecessor-version":[{"id":2641,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/posts\/2619\/revisions\/2641"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/media?parent=2619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/categories?post=2619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/tags?post=2619"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/post_folder?post=2619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}