{"id":2838,"date":"2024-03-11T08:58:01","date_gmt":"2024-03-11T07:58:01","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/?p=2838"},"modified":"2024-03-11T08:58:28","modified_gmt":"2024-03-11T07:58:28","slug":"el-orienta","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/2024\/03\/11\/el-orienta\/","title":{"rendered":"EL ORIENTA"},"content":{"rendered":"<p><span style=\"color: #000000;\">Aqu\u00ed os dejamos el enlace de acceso al programa inform\u00e1tico que os ayudar\u00e1, de una manera sencilla y muy \u00fatil, a informaros (y orientaros) de cara a la toma de decisiones acad\u00e9mico-profesional, tal y como se habl\u00f3 en la charla de orientaci\u00f3n:<strong> <a href=\"https:\/\/www.orientaline.es\/?yafxb=66129\">EL ORIENTA.<\/a><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aqu\u00ed os dejamos el enlace de acceso al programa inform\u00e1tico que os ayudar\u00e1, de una manera sencilla y muy \u00fatil, a informaros (y orientaros) de cara a la toma de &#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-2838","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ies.lasencinas.villanuevadelacanada","author_link":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/author\/cuenta_ies-lasencinas-villanuevadelacanada\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"Aqu\u00ed os dejamos el enlace de acceso al programa inform\u00e1tico que os ayudar\u00e1, de una manera sencilla y muy \u00fatil, a informaros (y orientaros) de cara a la toma de ...","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/posts\/2838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/comments?post=2838"}],"version-history":[{"count":2,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/posts\/2838\/revisions"}],"predecessor-version":[{"id":2840,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/posts\/2838\/revisions\/2840"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/media?parent=2838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/categories?post=2838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/tags?post=2838"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/post_folder?post=2838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}