{"id":2916,"date":"2024-05-12T13:17:33","date_gmt":"2024-05-12T11:17:33","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/?p=2916"},"modified":"2024-06-23T09:42:44","modified_gmt":"2024-06-23T07:42:44","slug":"informacion-accede","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/2024\/05\/12\/informacion-accede\/","title":{"rendered":"INFORMACI\u00d3N ACCEDE"},"content":{"rendered":"\n<p><span style=\"color: #000000;\">Informaci\u00f3n sobre el pr\u00e9stamo de libros ACCEDE, de cara al fin de curso:<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400; color: #000000;\">. <strong>D\u00edas 17, 18 y 19 de junio<\/strong>: recogida de lotes para los alumnos que han disfrutado de pr\u00e9stamo, en horario de clase (se avisar\u00e1 con antelaci\u00f3n para que no se olviden los libros en casa). Tambi\u00e9n los que vayan a repetir curso.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400; color: #000000;\">. Los libros deber\u00e1n entregarse <strong>forrados y borrados<\/strong>, en caso de que se hayan hecho subrayados o anotaciones.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400; color: #000000;\">. Las familias adheridas al programa, una vez devueltos los libros, tendr\u00e1n que enviar el <strong>certificado de devoluci\u00f3n<\/strong> de los mismos (recordamos que <strong>NO deben pagar otra fianza<\/strong>). Se har\u00e1 entrega de los nuevos lotes de libros al inicio del curso siguiente.<\/span><\/p>\n\n\n\n<p class=\"has-black-color has-text-color\"><span style=\"color: #000000;\"><span style=\"font-weight: 400;\">. Las<strong> familias no adheridas al programa que quieran participar el pr\u00f3ximo curso<\/strong> (recordamos que el pr\u00e9stamo cubre solo la ESO y FP B\u00e1sica), deber\u00e1n hacernos llegar el <strong><a href=\"https:\/\/drive.google.com\/file\/d\/1GjaJlbmgjQfkMSqQXqmSdu4McJndgMi7\/view?usp=sharing\">ANEXO I<\/a> <\/strong>al correo <\/span><a style=\"color: #000000;\" href=\"mailto:accede@ieslasencinas.es\"><span style=\"font-weight: 400;\"><strong>accede@ieslasencinas.es<\/strong><\/span><\/a><\/span> junto con el <strong>certificado de haber donado<\/strong> sus libros del curso finalizado. Se les facilitar\u00e1 el n\u00famero de cuenta para el ingreso de la fianza y tendr\u00e1n que enviar justificante de pago de la misma.<\/p>\n\n\n\n<p><span style=\"color: #000000;\"><span style=\"font-weight: 400;\">. Las familias del alumnado que finalice 4\u00ba ESO o 2\u00ba de FP B\u00e1sica, o que cambien de centro o que quieran darse de <strong>baja del programa,<\/strong> deben escribir a <\/span><a style=\"color: #000000;\" href=\"mailto:accede@ieslasencinas.es\"><span style=\"font-weight: 400;\">accede@ieslasencinas.es<\/span><\/a><span style=\"font-weight: 400;\">, con los <strong>datos bancarios<\/strong> que se les ha solicitado por correo (nombre y apellidos y DNI del titular de la cuenta, iban y n\u00famero de cuenta), m\u00e1s el <strong>certificado de devoluci\u00f3n<\/strong> de los libros prestados, para que se les pueda devolver la fianza a lo largo del mes de julio.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informaci\u00f3n sobre el pr\u00e9stamo de libros ACCEDE, de cara al fin de curso: . D\u00edas 17, 18 y 19 de junio: recogida de lotes para los alumnos que han disfrutado &#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-2916","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ies.lasencinas.villanuevadelacanada","author_link":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/author\/cuenta_ies-lasencinas-villanuevadelacanada\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"Informaci\u00f3n sobre el pr\u00e9stamo de libros ACCEDE, de cara al fin de curso: . D\u00edas 17, 18 y 19 de junio: recogida de lotes para los alumnos que han disfrutado ...","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/posts\/2916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/comments?post=2916"}],"version-history":[{"count":6,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/posts\/2916\/revisions"}],"predecessor-version":[{"id":2988,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/posts\/2916\/revisions\/2988"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/media?parent=2916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/categories?post=2916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/tags?post=2916"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lasencinas.villanuevadelacanada\/index.php\/wp-json\/wp\/v2\/post_folder?post=2916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}