{"id":29,"count":3,"description":"","link":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/category\/aro\/","name":"aro","slug":"aro","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/categories\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts?categories=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}