{"id":4957,"date":"2022-11-17T18:53:38","date_gmt":"2022-11-17T17:53:38","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/?p=4957"},"modified":"2022-11-17T18:53:38","modified_gmt":"2022-11-17T17:53:38","slug":"i-torneo-amistoso-esgrima-lazaro-cardenas","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/2022\/11\/17\/i-torneo-amistoso-esgrima-lazaro-cardenas\/","title":{"rendered":"I TORNEO AMISTOSO ESGRIMA L\u00c1ZARO C\u00c1RDENAS"},"content":{"rendered":"\n<p>El pasado domingo 6 de Abril tuvo lugar en el IES L\u00e1zaro C\u00e1rdenas nuestro primer torneo amistoso de esgrima en categor\u00edas sub6, sub8, sub10 y sub12.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado domingo 6 de Abril tuvo lugar en el IES L\u00e1zaro C\u00e1rdenas nuestro primer torneo amistoso de esgrima en categor\u00edas sub6, sub8, sub10 y sub12.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-4957","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ies.lazarocardenas.colladovillalba","author_link":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/author\/cuenta_ies-lazarocardenas-colladovillalba\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"El pasado domingo 6 de Abril tuvo lugar en el IES L\u00e1zaro C\u00e1rdenas nuestro primer torneo amistoso de esgrima en categor\u00edas sub6, sub8, sub10 y sub12.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/4957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/comments?post=4957"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/4957\/revisions"}],"predecessor-version":[{"id":4958,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/4957\/revisions\/4958"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/media?parent=4957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/categories?post=4957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/tags?post=4957"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/post_folder?post=4957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}