{"id":4980,"date":"2022-11-17T19:08:25","date_gmt":"2022-11-17T18:08:25","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/?p=4980"},"modified":"2022-11-17T19:08:25","modified_gmt":"2022-11-17T18:08:25","slug":"encuentro-con-joan-manuel-gisbert","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/2022\/11\/17\/encuentro-con-joan-manuel-gisbert\/","title":{"rendered":"ENCUENTRO CON JOAN MANUEL GISBERT"},"content":{"rendered":"\n<p>El 14 de febrero DE 2014, alumnos de 2\u00ba ESO tuvieron un encuentro literario con el escritor Joan Manuel Gisbert. Aqu\u00ed puedes leer una breve rse\u00f1a del acto realizada por el alumno \u00c1lvaro Cort\u00e9s L\u00f3pez de 2\u00ba A ESO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 14 de febrero DE 2014, alumnos de 2\u00ba ESO tuvieron un encuentro literario con el escritor Joan Manuel Gisbert. Aqu\u00ed puedes leer una breve rse\u00f1a del acto realizada por el alumno \u00c1lvaro Cort\u00e9s L\u00f3pez de 2\u00ba A ESO.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-4980","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ies.lazarocardenas.colladovillalba","author_link":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/author\/cuenta_ies-lazarocardenas-colladovillalba\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"El 14 de febrero DE 2014, alumnos de 2\u00ba ESO tuvieron un encuentro literario con el escritor Joan Manuel Gisbert. Aqu\u00ed puedes leer una breve rse\u00f1a del acto realizada por el alumno \u00c1lvaro Cort\u00e9s L\u00f3pez de 2\u00ba A ESO.","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/4980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/comments?post=4980"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/4980\/revisions"}],"predecessor-version":[{"id":4981,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/4980\/revisions\/4981"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/media?parent=4980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/categories?post=4980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/tags?post=4980"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/post_folder?post=4980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}