{"id":4991,"date":"2022-11-17T19:14:31","date_gmt":"2022-11-17T18:14:31","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/?p=4991"},"modified":"2022-11-17T19:14:31","modified_gmt":"2022-11-17T18:14:31","slug":"congreso-de-trabajos-de-investigacion","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/2022\/11\/17\/congreso-de-trabajos-de-investigacion\/","title":{"rendered":"CONGRESO DE TRABAJOS DE INVESTIGACI\u00d3N"},"content":{"rendered":"\n<p>Dos alumnos de nuestro centro,\u00a0<strong>Cristina Imaz Chac\u00f3n<\/strong>\u00a0y\u00a0<strong>Santiago S\u00e1nchez Qu\u00edlez<\/strong>, fueron seleccionados para participar en un Congreso de Proyectos de Investigaci\u00f3n de alumnos de Secundaria y Bachillerato organizado por el IES Ramiro de Maeztu. <\/p>\n\n\n\n<p>Los pasados 18 y 19 de Abril de 2016 presentaron p\u00fablicamente sus trabajos. <a href=\"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/proyectos-de-investigacion-bachillerato\/\">M\u00e1s informaci\u00f3n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos alumnos de nuestro centro,\u00a0Cristina Imaz Chac\u00f3n\u00a0y\u00a0Santiago S\u00e1nchez Qu\u00edlez, fueron seleccionados para participar en un Congreso de Proyectos de Investigaci\u00f3n de alumnos de Secundaria y Bachillerato organizado por el IES Ramiro de Maeztu. Los pasados 18 y 19 de Abril de 2016 presentaron p\u00fablicamente sus trabajos. M\u00e1s informaci\u00f3n<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-4991","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ies.lazarocardenas.colladovillalba","author_link":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/author\/cuenta_ies-lazarocardenas-colladovillalba\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"Dos alumnos de nuestro centro,\u00a0Cristina Imaz Chac\u00f3n\u00a0y\u00a0Santiago S\u00e1nchez Qu\u00edlez, fueron seleccionados para participar en un Congreso de Proyectos de Investigaci\u00f3n de alumnos de Secundaria y Bachillerato organizado por el IES Ramiro de Maeztu. Los pasados 18 y 19 de Abril de 2016 presentaron p\u00fablicamente sus trabajos. M\u00e1s informaci\u00f3n","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/4991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/comments?post=4991"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/4991\/revisions"}],"predecessor-version":[{"id":4992,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/4991\/revisions\/4992"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/media?parent=4991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/categories?post=4991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/tags?post=4991"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/post_folder?post=4991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}