{"id":5053,"date":"2022-11-17T19:41:51","date_gmt":"2022-11-17T18:41:51","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/?p=5053"},"modified":"2022-11-17T19:41:51","modified_gmt":"2022-11-17T18:41:51","slug":"viaje-a-bruselas","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/2022\/11\/17\/viaje-a-bruselas\/","title":{"rendered":"VIAJE A BRUSELAS"},"content":{"rendered":"\n<p>Un grupo de 15 alumnos y dos profesores de Administraci\u00f3n y Finanzas visitan la sede del&nbsp;<strong>Parlamento Europeo en Bruselas<\/strong>, del 29 al 31 de enero.<\/p>\n\n\n\n<p>Adem\u00e1s de conocer de primera mano, una de las sedes del poder legislativo europeo (la otra est\u00e1 en Estrasburgo) y el trabajo de los europarlamentarios, tambi\u00e9n han aprovechado para visitar Gante y Brujas<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Familia Profesional Administraci\u00f3n y Gesti\u00f3n<\/h1>\n\n\n\n<p><strong>Ciclo Grado Medio.&nbsp;<\/strong>T\u00edtulo exigido: ESO, FP. B\u00e1sica o prueba de acceso<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Gesti\u00f3n Administrativa<\/strong>:&nbsp;<ul><li>Curso 1\u00ba Septiembre a Junio<\/li><li>Curso 2\u00ba Septiembre a Marzo. Pr\u00e1cticas de FCT Marzo\/Junio<\/li><\/ul><\/li><li><strong>Gesti\u00f3n Administrativa (A distancia)<\/strong>:<ul><li>Curso 1\u00ba De Septiembre a Junio. En este curso se pueden estudiar todos lo m\u00f3dulos profesionales a excepci\u00f3n de FCT. Si no se superan todos los m\u00f3dulos profesionales en un curso, se repite curso y el alumno se matricula de los m\u00f3dulos no superados que desee.<\/li><li>FCT siguiente curso Octubre a Enero.<\/li><\/ul><\/li><\/ul>\n\n\n\n<p><strong>Ciclo Grado Superior.&nbsp;<\/strong>T\u00edtulo exigido: Bachillerato, t\u00e9cnico superior o prueba de acceso.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Administraci\u00f3n y Finanzas<\/strong>:&nbsp;<ul><li>Curso 1\u00ba Septiembre a Junio<\/li><li>Curso 2\u00ba Septiembre a Marzo, Pr\u00e1cticas de FCT Marzo\/Junio<\/li><\/ul><\/li><li><strong>Asistente a la Direcci\u00f3n<\/strong>:&nbsp;<ul><li>Curso 1\u00ba Septiembre a Junio<\/li><li>Curso 2\u00ba Septiembre a Marzo, Pr\u00e1cticas de FCT Marzo\/Junio<\/li><\/ul><\/li><\/ul>\n\n\n\n<p>.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"549\" height=\"366\" data-id=\"5054\" src=\"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/1.jpg\" alt=\"\" class=\"wp-image-5054\" srcset=\"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/1.jpg 549w, https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/1-300x200.jpg 300w, https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/1-391x260.jpg 391w, https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/1-272x182.jpg 272w\" sizes=\"auto, (max-width: 549px) 100vw, 549px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de 15 alumnos y dos profesores de Administraci\u00f3n y Finanzas visitan la sede del&nbsp;Parlamento Europeo en Bruselas, del 29 al 31 de enero. Adem\u00e1s de conocer de primera mano, una de las sedes del poder legislativo europeo (la otra est\u00e1 en Estrasburgo) y el trabajo de los europarlamentarios, tambi\u00e9n han aprovechado para visitar &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/2022\/11\/17\/viaje-a-bruselas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abVIAJE A BRUSELAS\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-5053","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ies.lazarocardenas.colladovillalba","author_link":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/author\/cuenta_ies-lazarocardenas-colladovillalba\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"Un grupo de 15 alumnos y dos profesores de Administraci\u00f3n y Finanzas visitan la sede del&nbsp;Parlamento Europeo en Bruselas, del 29 al 31 de enero. Adem\u00e1s de conocer de primera mano, una de las sedes del poder legislativo europeo (la otra est\u00e1 en Estrasburgo) y el trabajo de los europarlamentarios, tambi\u00e9n han aprovechado para visitar&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/5053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/comments?post=5053"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/5053\/revisions"}],"predecessor-version":[{"id":5055,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/5053\/revisions\/5055"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/media?parent=5053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/categories?post=5053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/tags?post=5053"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/post_folder?post=5053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}