{"id":5093,"date":"2022-11-17T20:10:59","date_gmt":"2022-11-17T19:10:59","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/?p=5093"},"modified":"2022-11-30T17:02:04","modified_gmt":"2022-11-30T16:02:04","slug":"feria-de-la-ciencia","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/2022\/11\/17\/feria-de-la-ciencia\/","title":{"rendered":"FERIA DE LA CIENCIA\u00a0"},"content":{"rendered":"\n<p>Del 2 al 5 de marzo, alumnos de 3\u00b0A ESO y 2\u00b0PMAR han explicado en IFEMA su proyecto<strong>&nbsp;\u00abAbejas y arom\u00e1ticas: la coevoluci\u00f3n perfecta\u00bb<\/strong>&nbsp;tras ser seleccionados para mostrar su trabajo en un stand en la&nbsp;<strong><a href=\"https:\/\/www.madrimasd.org\/feriamadridesciencia2022\" target=\"_blank\" rel=\"noreferrer noopener\">XI Feria MadridesCiencia.<\/a><\/strong><\/p>\n\n\n\n<p><strong>FERIA DE LA CIENCIA 2022&nbsp;<\/strong><\/p>\n\n\n\n<p>Del 2 al 5 de marzo, alumnos de 3\u00b0A ESO y 2\u00b0PMAR han explicado en IFEMA su proyecto&nbsp;<strong>\u00abAbejas y arom\u00e1ticas: la coevoluci\u00f3n perfecta\u00bb.<\/strong><\/p>\n\n\n\n<p>En su stand de la&nbsp;<strong>XI Feria MadridesCiencia<\/strong>&nbsp;han participado tambi\u00e9n alumnos de 1\u00ba ESO que han aportado sus maquetas de insecto polinizadores. En la presentaci\u00f3n ten\u00e9is un resumen de estos d\u00edas de duro trabajo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 2 al 5 de marzo, alumnos de 3\u00b0A ESO y 2\u00b0PMAR han explicado en IFEMA su proyecto&nbsp;\u00abAbejas y arom\u00e1ticas: la coevoluci\u00f3n perfecta\u00bb&nbsp;tras ser seleccionados para mostrar su trabajo en un stand en la&nbsp;XI Feria MadridesCiencia. FERIA DE LA CIENCIA 2022&nbsp; Del 2 al 5 de marzo, alumnos de 3\u00b0A ESO y 2\u00b0PMAR han explicado &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/2022\/11\/17\/feria-de-la-ciencia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abFERIA DE LA CIENCIA\u00a0\u00ab<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":5094,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,1],"tags":[],"post_folder":[],"class_list":["post-5093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sin-categoria"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001.jpg",550,412,false],"landscape":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001.jpg",550,412,false],"portraits":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001.jpg",550,412,false],"thumbnail":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001-300x225.jpg",300,225,true],"large":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001.jpg",525,393,false],"thumblist":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001.jpg",500,375,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001.jpg",550,412,false],"2048x2048":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001.jpg",550,412,false],"twentyseventeen-featured-image":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001.jpg",550,412,false],"twentyseventeen-thumbnail-avatar":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001.jpg",100,75,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001.jpg",360,270,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001.jpg",320,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/\/wp-content\/uploads\/ies.lazarocardenas.colladovillalba\/2022\/11\/IMG-20220305-WA0001.jpg",550,412,false]},"rttpg_author":{"display_name":"ies.lazarocardenas.colladovillalba","author_link":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/author\/cuenta_ies-lazarocardenas-colladovillalba\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a> <a href=\"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"Del 2 al 5 de marzo, alumnos de 3\u00b0A ESO y 2\u00b0PMAR han explicado en IFEMA su proyecto&nbsp;\u00abAbejas y arom\u00e1ticas: la coevoluci\u00f3n perfecta\u00bb&nbsp;tras ser seleccionados para mostrar su trabajo en un stand en la&nbsp;XI Feria MadridesCiencia. FERIA DE LA CIENCIA 2022&nbsp; Del 2 al 5 de marzo, alumnos de 3\u00b0A ESO y 2\u00b0PMAR han explicado&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/5093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/comments?post=5093"}],"version-history":[{"count":1,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/5093\/revisions"}],"predecessor-version":[{"id":5095,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/posts\/5093\/revisions\/5095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/media\/5094"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/media?parent=5093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/categories?post=5093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/tags?post=5093"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.lazarocardenas.colladovillalba\/index.php\/wp-json\/wp\/v2\/post_folder?post=5093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}