{"id":1540,"date":"2021-10-25T18:59:25","date_gmt":"2021-10-25T16:59:25","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/?p=1540"},"modified":"2022-02-10T13:21:42","modified_gmt":"2022-02-10T12:21:42","slug":"actividades-de-tiempo-libre-noviembre-2021","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/2021\/10\/25\/actividades-de-tiempo-libre-noviembre-2021\/","title":{"rendered":"Actividades de tiempo libre noviembre 2021"},"content":{"rendered":"<div id=\"v1replybody1\">\n<div>\n<div id=\"v1v1forwardbody1\">\n<div lang=\"ES\">\n<div class=\"v1v1v1WordSection1\">\n<p class=\"v1v1v1MsoNormal\">\u00a1Buenas tardes!<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"v1replybody1\">\n<div>\n<div id=\"v1v1forwardbody1\">\n<div lang=\"ES\">\n<div class=\"v1v1v1WordSection1\">\n<p class=\"v1v1v1MsoNormal\">Ya est\u00e1 disponible la programaci\u00f3n de\u00a0<strong>\u00a0 NOVIEMBRE 2021\u00a0<\/strong>de las\u00a0<strong>ACTIVIDADES DE TIEMPO LIBRE DE LA CONCEJAL\u00cdA DE EDUCACI\u00d3N Y\u00a0JUVENTUD<\/strong>.<\/p>\n<p class=\"v1v1v1MsoNormal\">&#8211; \u00a0Actividad para\u00a0<strong>familias<\/strong>\u00a0(con hijos\/as\u00a0de 5 a 17 a\u00f1os). \u2013\u00a0<a href=\"https:\/\/www.mostolesjoven.es\/es\/juventud\/programas\/tiempo-libre\/actividades-tiempo-libre-noviembre\/familias-hayedo-pedrosa\" target=\"_blank\" rel=\"noopener noreferrer\">HAYEDO DE LA PEDROSA.<\/a><\/p>\n<p class=\"v1v1v1MsoNormal\">&#8211;\u00a0\u00a0Actividad para\u00a0<strong>j\u00f3venes<\/strong>\u00a0(18 a 35 a\u00f1os). \u2013\u00a0<a href=\"https:\/\/www.mostolesjoven.es\/es\/juventud\/programas\/tiempo-libre\/actividades-tiempo-libre-noviembre\/jovenes-via-verde-jara\" target=\"_blank\" rel=\"noopener noreferrer\">V\u00cdA VERDE DE LA JARA<\/a>.<\/p>\n<p class=\"v1v1v1MsoNormal\">&#8211;\u00a0 Actividad para\u00a0<strong>adolescentes<\/strong>\u00a0(de 12 a 17 a\u00f1os). \u2013\u00a0<a href=\"https:\/\/www.mostolesjoven.es\/es\/juventud\/programas\/tiempo-libre\/actividades-tiempo-libre-noviembre\/adolescentes-orientacion\" target=\"_blank\" rel=\"noopener noreferrer\">T\u00c9CNICAS DE ORIENTACI\u00d3N EN LA MONTA\u00d1A.<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"v1replybody1\">\n<div>\n<div id=\"v1v1forwardbody1\">\n<div lang=\"ES\">\n<div class=\"v1v1v1WordSection1\">\n<p class=\"v1v1v1MsoNormal\">Consulta\u00a0la\u00a0<strong>programaci\u00f3n<\/strong>, pinchando\u00a0<strong><a href=\"https:\/\/www.mostolesjoven.es\/es\/juventud\/programas\/tiempo-libre\/actividades-tiempo-libre-noviembre\" target=\"_blank\" rel=\"noopener noreferrer\">AQU\u00cd<\/a><\/strong>:<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"v1replybody1\">\n<div>\n<div id=\"v1v1forwardbody1\">\n<div lang=\"ES\">\n<div class=\"v1v1v1WordSection1\">\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/correoweb.educa.madrid.org\/?_task=mail&amp;_action=get&amp;_mbox=INBOX.Enviados&amp;_uid=1717&amp;_token=Lx9t5McYnBZKhGgZKgdlbCajzBhrh7qJ&amp;_part=2.2&amp;_embed=1&amp;_mimeclass=image\" \/><\/p>\n<div id=\"v1replybody1\">\n<div>\n<div id=\"v1v1forwardbody1\">\n<div lang=\"ES\">\n<div class=\"v1v1v1WordSection1\">\n<p class=\"v1v1v1MsoNormal\">Para participar en las actividades es necesario realizar\u00a0<strong>PREINSCRIPCI\u00d3N<\/strong>, a trav\u00e9s del correo electr\u00f3nico:\u00a0<a href=\"mailto:INSCRIPCIONES-JUVENTUD@mostoles.es\" rel=\"noreferrer\">INSCRIPCIONES-JUVENTUD@mostoles.es<\/a>, en las siguientes fechas:<\/p>\n<p class=\"v1v1v1MsoNormal\">\n<p class=\"v1v1v1MsoListParagraph\"><strong>&#8211;<u>\u00a0Familias<\/u>.\u00a0&#8211;<\/strong>\u00a0A partir del d\u00eda\u00a0<strong>20 de octubre<\/strong>\u00a0a las 10:00 h (los correos entrantes anteriores a la fecha y hora, NO ser\u00e1n tenidos en cuenta) hasta el\u00a0<strong><u>22 de octubre<\/u><\/strong><u>\u00a0a las 14:00 h<\/u>.<\/p>\n<p class=\"v1v1v1MsoNormal\">Esta actividad est\u00e1 sujeta a SORTEO, que se celebra el d\u00eda\u00a0<strong>27 de octubre,\u00a0<\/strong>a las 11:00 h<\/p>\n<p class=\"v1v1v1MsoNormal\"><strong>ASUNTO MAIL:<\/strong>\u00a0<em>Familias + Nombre y apellidos.<\/em><\/p>\n<p class=\"v1v1v1MsoNormal\"><strong>Datos a aporta<\/strong>r: Nombre y Apellidos del representante de la unidad familiar, edades de los miembros de la unidad familiar que van a participar y tel\u00e9fono de contacto.<\/p>\n<p class=\"v1v1v1MsoListParagraph\"><strong>&#8211;\u00a0<u>J\u00f3venes<\/u>.<\/strong>\u00a0&#8211; A partir del d\u00eda\u00a0<strong>25 de octubre<\/strong>\u00a0a las 10:00 h (los correos entrantes anteriores a la fecha y hora NO ser\u00e1n tenidos en cuenta).<\/p>\n<p class=\"v1v1v1MsoNormal\"><strong>ASUNTO MAIL:<\/strong>\u00a0<em>J\u00f3venes + Nombre y apellidos.<\/em><\/p>\n<p class=\"v1v1v1MsoNormal\"><strong>Datos a aporta<\/strong>r: Nombre y Apellidos del participante, edad y tel\u00e9fono.<\/p>\n<p class=\"v1v1v1MsoListParagraph\"><strong>&#8211;\u00a0<u>Adolescentes<\/u><\/strong>.\u00a0&#8211; A partir del d\u00eda\u00a0<strong>28 de octubre<\/strong>\u00a0a las 10:00 h (los correos entrantes anteriores a la fecha y hora, NO ser\u00e1n tenidos en cuenta).<\/p>\n<p class=\"v1v1v1MsoNormal\"><strong>ASUNTO MAIL:<\/strong>\u00a0<em>Adolescentes + Nombre y apellidos.<\/em><\/p>\n<p class=\"v1v1v1MsoNormal\"><strong>Datos a aporta<\/strong>r: Nombre y Apellidos del menor, edad y tel\u00e9fono.<\/p>\n<p class=\"v1v1v1MsoNormal\"><strong>NOTA. &#8211; RECUERDA QUE\u00a0<u>DEBES ESTAR EMPADRONADO EN M\u00d3STOLES<\/u>\u00a0(los\/as interesados\/as de FUERA DE M\u00d3STOLES, pasar\u00e1n a una LISTA DE ESPERA).<\/strong><\/p>\n<p class=\"v1v1v1MsoNormal\">Una vez recibido la petici\u00f3n de plaza, se le enviar\u00e1 un correo de confirmaci\u00f3n de la misma al participante con las indicaciones necesarias para realizar la\u00a0<strong>INSCRIPCI\u00d3N DEFINITIVA.<\/strong><\/p>\n<p class=\"v1v1v1MsoNormal\">\u00a0Para m\u00e1s informaci\u00f3n consulta en\u00a0\u00a0<a href=\"http:\/\/www.mostolesjoven.es\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.mostolesjoven.es<\/a>\u00a0\u00a0 o llamando al tel\u00e9fono:<\/p>\n<p class=\"v1v1v1MsoNormal\"><strong>91 618 16 16<\/strong>, de lunes a viernes de 10:00 a 14:00 h y de lunes a jueves de 17:00 a 20:00 h.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"v1replybody1\">\n<div>\n<div id=\"v1v1forwardbody1\">\n<div lang=\"ES\">\n<div class=\"v1v1v1WordSection1\">\n<div id=\"v1replybody1\">\n<div>\n<div id=\"v1v1forwardbody1\">\n<div lang=\"ES\">\n<div class=\"v1v1v1WordSection1\">\n<div id=\"v1replybody1\">\n<div>\n<div id=\"v1v1forwardbody1\">\n<div lang=\"ES\">\n<div class=\"v1v1v1WordSection1\">\n<p class=\"v1v1v1MsoNormal\">Tambi\u00e9n puedes realizar consultas a trav\u00e9s de\u00a0<strong>WHATSAPP<\/strong>, al n\u00ba de tel\u00e9fono:\u00a0<strong>680 74 66 49<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Buenas tardes! Ya est\u00e1 disponible la programaci\u00f3n de\u00a0\u00a0 NOVIEMBRE 2021\u00a0de las\u00a0ACTIVIDADES DE TIEMPO LIBRE DE LA CONCEJAL\u00cdA DE EDUCACI\u00d3N Y\u00a0JUVENTUD. &#8211; \u00a0Actividad para\u00a0familias\u00a0(con hijos\/as\u00a0de 5 a 17 a\u00f1os). \u2013\u00a0HAYEDO DE &#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77,38,1],"tags":[],"post_folder":[],"class_list":["post-1540","post","type-post","status-publish","format-standard","hentry","category-actividades","category-mostoles-joven","category-novedades"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Coordinador TIC del IES Manuela Malasa\u00f1a","author_link":"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/author\/cuenta_tic-ies-malasana-mostoles\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/category\/ensenanzas\/actividades\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/category\/ensenanzas\/actividades\/mostoles-joven\/\" rel=\"category tag\">M\u00f3stoles Joven<\/a> <a href=\"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/category\/novedades\/\" rel=\"category tag\">Novedades<\/a>","rttpg_excerpt":"\u00a1Buenas tardes! Ya est\u00e1 disponible la programaci\u00f3n de\u00a0\u00a0 NOVIEMBRE 2021\u00a0de las\u00a0ACTIVIDADES DE TIEMPO LIBRE DE LA CONCEJAL\u00cdA DE EDUCACI\u00d3N Y\u00a0JUVENTUD. &#8211; \u00a0Actividad para\u00a0familias\u00a0(con hijos\/as\u00a0de 5 a 17 a\u00f1os). \u2013\u00a0HAYEDO DE ...","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/wp-json\/wp\/v2\/posts\/1540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/wp-json\/wp\/v2\/comments?post=1540"}],"version-history":[{"count":3,"href":"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/wp-json\/wp\/v2\/posts\/1540\/revisions"}],"predecessor-version":[{"id":1543,"href":"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/wp-json\/wp\/v2\/posts\/1540\/revisions\/1543"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/wp-json\/wp\/v2\/media?parent=1540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/wp-json\/wp\/v2\/categories?post=1540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/wp-json\/wp\/v2\/tags?post=1540"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.malasana.mostoles\/index.php\/wp-json\/wp\/v2\/post_folder?post=1540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}