{"id":114,"date":"2020-06-17T15:19:18","date_gmt":"2020-06-17T15:19:18","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/?page_id=114"},"modified":"2026-03-05T10:55:01","modified_gmt":"2026-03-05T09:55:01","slug":"ensenanzas","status":"publish","type":"page","link":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/informacion-a-las-familias\/ensenanzas\/","title":{"rendered":"Ense\u00f1anzas"},"content":{"rendered":"\n<p class=\"has-black-color has-luminous-vivid-amber-background-color has-text-color has-background has-link-color wp-elements-02c177fc051667ef15280dd38efa0131\">ATENCI\u00d3N: la informaci\u00f3n de esta p\u00e1gina <strong>SE EST\u00c1 ACTUALIZANDO<\/strong>. Los ciclos de la modalidad intensiva todav\u00eda no est\u00e1n actualizados.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-group alignwide has-vivid-red-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h1 class=\"wp-block-heading has-text-align-center\"><br><span class=\"has-inline-color has-very-light-gray-color\"><strong>Modalidad Intensiva<\/strong><\/span><\/h1>\n\n\n\n<p class=\"has-text-align-center\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-very-light-gray-color\">Ciclos de dos cursos de duraci\u00f3n.<br>El primero se imparte enteramente en el centro.<br>El segundo se imparte enteramente en empresa.<\/mark><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-black-background-color has-text-color has-background\"><a href=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2022\/06\/DualVsPresencial_V3-1-1.jpg\">Diferencias entre Modalidad Presencial General y Modalidad Presencial Intensiva<\/a><\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile is-image-fill-element has-background\" style=\"background-color:#eeeeee;grid-template-columns:auto 39%\"><div class=\"wp-block-media-text__content\">\n<p class=\"has-very-dark-gray-color has-text-color has-large-font-size\">Actividades F\u00edsicas y Deportivas<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/afds01_acondicionamiento_fisico_0.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00e9cnico superior en Acondicionamiento F\u00edsico<\/a><\/strong> (plan de estudios presencial)<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.comunidad.madrid\/sites\/default\/files\/afds02_ensenanza_y_animacion_sociodeportiva_0.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00e9cnico superior en Ense\u00f1anza y Animaci\u00f3n Sociodeportiva<\/a><\/strong> (plan de estudios presencial)<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-small-font-size\">(Los enlaces apuntan al plan de estudios. En la ficha, la distribuci\u00f3n de las asignaturas en los cursos no se corresponde a la de este ciclo en el IES Rosa Chacel por ser modalidad dual intensiva)<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/deporte-1024x683.jpg\" alt=\"\" class=\"wp-image-93 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/deporte-1024x683.jpg 1024w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/deporte-300x200.jpg 300w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/deporte-768x512.jpg 768w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/deporte-700x467.jpg 700w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/deporte-520x347.jpg 520w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/deporte-360x240.jpg 360w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/deporte-250x167.jpg 250w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/deporte-100x67.jpg 100w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/deporte.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile is-image-fill-element has-background\" style=\"background-color:#eeeeee;grid-template-columns:auto 39%\"><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-left has-very-dark-gray-color has-text-color has-large-font-size\">Inform\u00e1tica y Comunicaciones<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/ifcm01_sistemas_microinformaticos_y_redes.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00e9cnico en Sistemas Microinform\u00e1ticos y Redes<\/a><\/strong> (plan de estudios presencial)<\/p>\n\n\n\n<p class=\"has-very-dark-gray-color has-text-color has-small-font-size\">(El enlace apunta al plan de estudios. En la ficha, la distribuci\u00f3n de las asignaturas en los cursos no se corresponde a la de este ciclo en el IES Rosa Chacel por ser modalidad dual intensiva)<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"910\" height=\"607\" src=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/informatica.jpg\" alt=\"\" class=\"wp-image-94 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/informatica.jpg 910w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/informatica-300x200.jpg 300w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/informatica-768x512.jpg 768w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/informatica-700x467.jpg 700w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/informatica-520x347.jpg 520w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/informatica-360x240.jpg 360w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/informatica-250x167.jpg 250w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/informatica-100x67.jpg 100w\" sizes=\"auto, (max-width: 910px) 100vw, 910px\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-very-dark-gray-color has-css-opacity has-very-dark-gray-background-color has-background is-style-dots\"\/>\n\n\n\n<div class=\"wp-block-group alignwide has-vivid-red-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h1 class=\"wp-block-heading has-text-align-center has-white-color has-text-color\"><br><strong>Modalidad Presencial<\/strong><\/h1>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color\">Ciclos de dos cursos de duraci\u00f3n.<br>El primer curso y los primeros dos trimestres del segundo curso se imparte en el centro.<br>El \u00faltimo trimestre del segundo curso se imparte en empresa.<\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-black-background-color has-text-color has-background\"><a href=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2022\/06\/DualVsPresencial_V3-1-1.jpg\"><\/a><a href=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2022\/06\/DualVsPresencial_V3-1-1.jpg\">Diferencias entre Modalidad Presencial General y Modalidad Presencial Intensiva<\/a><\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-image-fill-element has-background\" style=\"background-color:#eeeeee;grid-template-columns:39% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"728\" height=\"485\" src=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/exercise-gymnasium-exercising-stretch-preview.jpg\" alt=\"\" class=\"wp-image-495 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/exercise-gymnasium-exercising-stretch-preview.jpg 728w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/exercise-gymnasium-exercising-stretch-preview-300x200.jpg 300w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/exercise-gymnasium-exercising-stretch-preview-700x466.jpg 700w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/exercise-gymnasium-exercising-stretch-preview-520x346.jpg 520w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/exercise-gymnasium-exercising-stretch-preview-360x240.jpg 360w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/exercise-gymnasium-exercising-stretch-preview-250x167.jpg 250w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/exercise-gymnasium-exercising-stretch-preview-100x67.jpg 100w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-large-font-size\">Actividades F\u00edsicas y Deportivas<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/afdb01_acceso_y_conservacion_en_instalaciones_deportivas_0.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Profesional B\u00e1sico en Acceso y conservaci\u00f3n en instalaciones deportivas<\/strong> <\/a><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/afdm02_guia_en_el_medio_natural_y_de_tiempo_libre.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00e9cnico en Gu\u00eda en el Medio Natural y de Tiempo Libre<\/a><\/strong><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ver optativas<\/summary>\n<p class=\"has-small-font-size\">1\u00ba Ampliaci\u00f3n de t\u00e9cnicas de tiempo libre<br>2\u00ba Ampliaci\u00f3n de gu\u00eda en el medio natural acu\u00e1tico<\/p>\n<\/details>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/afds01_acondicionamiento_fisico_0.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>T\u00e9cnico superior en Acondicionamiento F\u00edsico<\/strong> <\/a><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ver optativas<\/summary>\n<p class=\"has-small-font-size\">1\u00ba Ampliaci\u00f3n de actividades b\u00e1sicas de acondicionamiento f\u00edsico con soporte musical<br>2\u00ba Nutrici\u00f3n deportiva<\/p>\n<\/details>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/afds02_ensenanza_y_animacion_sociodeportiva_0.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>T\u00e9cnico superior en Ense\u00f1anza y Animaci\u00f3n Sociodeportiva<\/strong> (BILING\u00dcISMO en <strong>INGL\u00c9S<\/strong>)<\/a><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ver optativas y asignaturas en ingl\u00e9s<\/summary>\n<p class=\"has-small-font-size\">OPTATIVAS<br>1\u00ba Habilidades comunicativas en lengua extranjera profesional<br>2\u00ba Actividades emergentes en centros de acondicionamiento<br><br>ASIGNATURAS IMPARTIDAS EN INGL\u00c9S<br>1\u00ba Dinamizaci\u00f3n grupal (3 horas\/semana)<br>2\u00ba Actividades de ocio y tiempo libre (7 horas\/semana)<\/p>\n<\/details>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-image-fill-element has-background\" style=\"background-color:#eeeeee;grid-template-columns:39% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/laptop_human_hands_keyboard_typing_working_business_office_writing-714530.jpgd_-1024x683.jpg\" alt=\"\" class=\"wp-image-496 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/laptop_human_hands_keyboard_typing_working_business_office_writing-714530.jpgd_-1024x683.jpg 1024w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/laptop_human_hands_keyboard_typing_working_business_office_writing-714530.jpgd_-300x200.jpg 300w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/laptop_human_hands_keyboard_typing_working_business_office_writing-714530.jpgd_-768x512.jpg 768w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/laptop_human_hands_keyboard_typing_working_business_office_writing-714530.jpgd_-700x467.jpg 700w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/laptop_human_hands_keyboard_typing_working_business_office_writing-714530.jpgd_-520x347.jpg 520w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/laptop_human_hands_keyboard_typing_working_business_office_writing-714530.jpgd_-360x240.jpg 360w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/laptop_human_hands_keyboard_typing_working_business_office_writing-714530.jpgd_-250x167.jpg 250w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/laptop_human_hands_keyboard_typing_working_business_office_writing-714530.jpgd_-100x67.jpg 100w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/07\/laptop_human_hands_keyboard_typing_working_business_office_writing-714530.jpgd_.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-left has-black-color has-text-color has-large-font-size\">Inform\u00e1tica y Comunicaciones<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/ifcb02_informatica_de_oficina.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Profesional b\u00e1sico en Inform\u00e1tica de Oficina<\/strong> <\/a><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/ifcm01_sistemas_microinformaticos_y_redes.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>T\u00e9cnico en Sistemas Microinform\u00e1ticos y Redes<\/strong> <\/a><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ver optativas<\/summary>\n<p class=\"has-small-font-size\"><strong>Optativas A: <br><\/strong>1\u00ba Fundamentos de bases de datos <br>2\u00ba Ciberseguridad<br><strong>Optativas B:<br><\/strong>1\u00ba Fundamentos de programaci\u00f3n<br>2\u00ba Programaci\u00f3n en Python<\/p>\n<\/details>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/ifcs01_administracion_de_sistemas_informaticos_en_red.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>T\u00e9cnico superior en Administraci\u00f3n de Sistemas Inform\u00e1ticos en Red<\/strong> <\/a><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ver optativas<\/summary>\n<p class=\"has-small-font-size\">1\u00ba Fundamentos de Computaci\u00f3n en la nube<br>2\u00ba Arquitectura en la nube <\/p>\n<\/details>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/ifcs02_desarrollo_de_aplicaciones_multiplataforma.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>T\u00e9cnico superior en Desarrollo de Aplicaciones Multiplataforma<\/strong> <\/a><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ver optativas<\/summary>\n<p class=\"has-small-font-size\">1\u00ba Ampliaci\u00f3n de programaci\u00f3n<br>2\u00ba Programaci\u00f3n de Videojuegos<\/p>\n<\/details>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/ifcs03_desarrollo_de_aplicaciones_web.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>T\u00e9cnico superior en Desarrollo de Aplicaciones Web<\/strong> <\/a><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ver optativas<\/summary>\n<p class=\"has-small-font-size\">1\u00ba Ampliaci\u00f3n de Programaci\u00f3n<br>2\u00ba Ampliaci\u00f3n de base de datos<\/p>\n<\/details>\n\n\n\n<p class=\"has-small-font-size\"><\/p>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-image-fill-element has-background\" style=\"background-color:#eeeeee;grid-template-columns:39% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"720\" src=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/sanidad.jpg\" alt=\"\" class=\"wp-image-95 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/sanidad.jpg 720w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/sanidad-300x300.jpg 300w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/sanidad-150x150.jpg 150w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/sanidad-700x700.jpg 700w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/sanidad-520x520.jpg 520w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/sanidad-360x360.jpg 360w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/sanidad-250x250.jpg 250w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/06\/sanidad-100x100.jpg 100w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-large-font-size\">Sanidad<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/www.comunidad.madrid\/sites\/default\/files\/doc\/educacion\/fp\/FP-Ensenanza-SAN201-LOGSE-Ficha.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00e9cnico en Cuidados Auxiliares de Enfermeria<\/a><\/strong> <br>(Ciclo LOGSE de 1 a\u00f1o de duraci\u00f3n)<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/sanm01_farmacia_y_parafarmacia.pdf\">T\u00e9cnico en Farmacia y Parafarmacia<\/a><\/strong><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ver optativas<\/summary>\n<p class=\"has-small-font-size\">1\u00ba Introducci\u00f3n a la Dispensaci\u00f3n de productos farmac\u00e9uticos<br>2\u00ba Farmacia hospitalaria<\/p>\n<\/details>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/sanm02_emergencias_sanitarias.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00e9cnico en Emergencias Sanitarias<\/a><\/strong><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ver optativas<\/summary>\n<p class=\"has-small-font-size\">1\u00ba Ampliaci\u00f3n a la asistencia sanitaria inicial en situaci\u00f3n de emergencia<br>2\u00ba Ampliaci\u00f3n a la asistencia sanitaria especial en situaciones de emergencia<\/p>\n<\/details>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/sans04_anatomia_patologica_y_citodiagnostico.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>T\u00e9cnico superior en Anatom\u00eda patol\u00f3gica y citodiagn\u00f3stico<\/strong> <\/a><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ver optativas<\/summary>\n<p class=\"has-small-font-size\">1\u00ba Introducci\u00f3n a la citolog\u00eda general<br>2\u00ba Ampliaci\u00f3n de citolog\u00eda general<\/p>\n<\/details>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/sans06_higiene_bucodental.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>T\u00e9cnico superior en Higiene Bucodental<\/strong> <\/a><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ver optativas<\/summary>\n<p class=\"has-small-font-size\">1\u00ba Introducci\u00f3n a la odontolog\u00eda conservadora, periodoncia, cirug\u00eda e implantes<br>2\u00ba Odontopediatr\u00eda<\/p>\n<\/details>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-image-fill-element has-background\" style=\"background-color:#eeeeee;grid-template-columns:39% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"882\" src=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2021\/06\/together-235128_1280-1024x882.jpg\" alt=\"\" class=\"wp-image-902 size-full\" style=\"object-position:55% 44%\" srcset=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2021\/06\/together-235128_1280-1024x882.jpg 1024w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2021\/06\/together-235128_1280-300x258.jpg 300w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2021\/06\/together-235128_1280-768x661.jpg 768w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2021\/06\/together-235128_1280-700x603.jpg 700w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2021\/06\/together-235128_1280-520x448.jpg 520w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2021\/06\/together-235128_1280-360x310.jpg 360w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2021\/06\/together-235128_1280-250x215.jpg 250w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2021\/06\/together-235128_1280-100x86.jpg 100w, https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2021\/06\/together-235128_1280.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-large-font-size\">Servicios Socioculturales y a la Comunidad<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/sscm01_atencion_a_personas_en_situacion_de_dependencia.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>T\u00e9cnico en Atenci\u00f3n a Personas en Situaci\u00f3n de Dependencia<\/strong> <\/a><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ver optativas<\/summary>\n<p class=\"has-small-font-size\">1\u00ba Metodolog\u00eda activas e innovaci\u00f3n en educaci\u00f3n infantil<br>2\u00ba Ampliaci\u00f3n de organizaci\u00f3n de la atenci\u00f3n a personas en situaci\u00f3n de dependencia<\/p>\n<\/details>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/comunidad.madrid\/sites\/default\/files\/sscs03_integracion_social.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>T\u00e9cnico superior en Integraci\u00f3n Social<\/strong> <\/a><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Ver optativas<\/summary>\n<p class=\"has-small-font-size\">1\u00ba Intervenci\u00f3n socioeducativa en el \u00e1mbito de la cooperaci\u00f3n internacional<br>2\u00ba Ampliaci\u00f3n de habilidades sociales<\/p>\n<\/details>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-background\" style=\"background-color:#eeeeee\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group has-white-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-file aligncenter\"><a id=\"wp-block-file--media-f23a98f8-9409-419a-85cf-e43bbe64d002\" href=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/09\/TR\u00cdPTICO_FP_Preguntas_frecuentes.pdf\"><br>Preguntas Frecuentes FP<\/a><a href=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2020\/09\/TR\u00cdPTICO_FP_Preguntas_frecuentes.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-f23a98f8-9409-419a-85cf-e43bbe64d002\">Descarga<\/a><\/div>\n\n\n\n<div class=\"wp-block-file aligncenter\"><a id=\"wp-block-file--media-c81ac8e0-ae25-49e9-850d-7eb97c6f798a\" href=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2022\/06\/DualVsPresencial_V3-1-1.jpg\">Diferencias entre Presencial y Presencial DUAL<\/a><a href=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/\/wp-content\/uploads\/ies.rosachacel.madrid\/2022\/06\/DualVsPresencial_V3-1-1.jpg\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-c81ac8e0-ae25-49e9-850d-7eb97c6f798a\">Descarga<\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>ATENCI\u00d3N: la informaci\u00f3n de esta p\u00e1gina SE EST\u00c1 ACTUALIZANDO. Los ciclos de la modalidad intensiva todav\u00eda no est\u00e1n actualizados. Modalidad Intensiva Ciclos de dos cursos de duraci\u00f3n.El primero se imparte enteramente en el centro.El segundo se imparte enteramente en empresa. Diferencias entre Modalidad Presencial General y Modalidad Presencial Intensiva Actividades F\u00edsicas y Deportivas T\u00e9cnico superior<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/informacion-a-las-familias\/ensenanzas\/\" class=\"home-blog-btn\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":2011,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"folder":[],"class_list":["post-114","page","type-page","status-publish","hentry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"tic.ies.rosachacel.madrid","author_link":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/author\/cuenta_tic-ies-rosachacel-madrid\/"},"rttpg_comment":0,"rttpg_category":false,"rttpg_excerpt":"ATENCI\u00d3N: la informaci\u00f3n de esta p\u00e1gina SE EST\u00c1 ACTUALIZANDO. Los ciclos de la modalidad intensiva todav\u00eda no est\u00e1n actualizados. Modalidad Intensiva Ciclos de dos cursos de duraci\u00f3n.El primero se imparte enteramente en el centro.El segundo se imparte enteramente en empresa. Diferencias entre Modalidad Presencial General y Modalidad Presencial Intensiva Actividades F\u00edsicas y Deportivas T\u00e9cnico superiorLeer&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/pages\/114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=114"}],"version-history":[{"count":50,"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/pages\/114\/revisions"}],"predecessor-version":[{"id":2665,"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/pages\/114\/revisions\/2665"}],"up":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/pages\/2011"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=114"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/folder?post=114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}