{"id":1948,"date":"2023-11-20T16:58:38","date_gmt":"2023-11-20T15:58:38","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/?p=1948"},"modified":"2023-11-20T17:04:12","modified_gmt":"2023-11-20T16:04:12","slug":"concurso-la-idea-mas-brillante-del-ies-rosa-chacel-de-madrid","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/2023\/11\/20\/concurso-la-idea-mas-brillante-del-ies-rosa-chacel-de-madrid\/","title":{"rendered":"Concurso \u201cLA IDEA M\u00c1S BRILLANTE DEL IES ROSA CHACEL DE MADRID\u201d"},"content":{"rendered":"<p>Este a\u00f1o, con el objetivo de impulsar y dar visibilidad al trabajo de los alumnos que cursan el m\u00f3dulo de Empresa e Iniciativa Emprendedora, el APE (Aula Profesional de Emprendimiento) en colaboraci\u00f3n con el Departamento de Formaci\u00f3n y Orientaci\u00f3n Laboral, organiza la primera edici\u00f3n del concurso <strong>\u201cLA IDEA M\u00c1S BRILLANTE DEL IES ROSA CHACEL\u201d.<\/strong><\/p>\n<p>En la primera fase (ya concluida) se ha elegido la mejor idea emprendedora de cada clase en las que se imparte el m\u00f3dulo de EIE.<\/p>\n<p>Ahora entramos en la segunda fase, en la que todos los alumnos del IES pod\u00e9is participar.<\/p>\n<p>\u00bfQuieres decirnos cu\u00e1l es la idea que te parece m\u00e1s brillante? An\u00edmate!, solo te llevar\u00e1 unos minutos.<\/p>\n<p style=\"text-align: center;\">Puedes acceder a la votaci\u00f3n con <a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=TrLhm6C2t028DNMzJWa_Mx9wXgZ1uSdLvn2vu3zc-bVUREQ0NVVYWVFJVjhKNUMwME82WUgwNDRZTy4u&amp;origin=QRCode\">este link<\/a> o escaneando este c\u00f3digo QR abajo<\/p>\n<p style=\"text-align: center;\">\u00a1Muchas gracias por tu colaboraci\u00f3n!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"shrinkToFit aligncenter\" src=\"https:\/\/correoweb.educa.madrid.org\/?_task=mail&amp;_mbox=INBOX&amp;_uid=4312&amp;_part=2&amp;_action=get&amp;_extwin=1&amp;_framed=1&amp;_mimewarning=1&amp;_embed=1\" alt=\"https:\/\/correoweb.educa.madrid.org\/?_task=mail&amp;_mbox=INBOX&amp;_uid=4312&amp;_part=2&amp;_action=get&amp;_extwin=1&amp;_framed=1&amp;_mimewarning=1&amp;_embed=1\" width=\"658\" height=\"658\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este a\u00f1o, con el objetivo de impulsar y dar visibilidad al trabajo de los alumnos que cursan el m\u00f3dulo de Empresa e Iniciativa Emprendedora, el APE (Aula Profesional de Emprendimiento) en colaboraci\u00f3n con el Departamento de Formaci\u00f3n y Orientaci\u00f3n Laboral, organiza la primera edici\u00f3n del concurso \u201cLA IDEA M\u00c1S BRILLANTE DEL IES ROSA CHACEL\u201d. En<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/2023\/11\/20\/concurso-la-idea-mas-brillante-del-ies-rosa-chacel-de-madrid\/\" class=\"home-blog-btn\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-1948","post","type-post","status-publish","format-standard","hentry","category-novedades"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"tic.ies.rosachacel.madrid","author_link":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/author\/cuenta_tic-ies-rosachacel-madrid\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/category\/novedades\/\" rel=\"category tag\">Novedades<\/a>","rttpg_excerpt":"Este a\u00f1o, con el objetivo de impulsar y dar visibilidad al trabajo de los alumnos que cursan el m\u00f3dulo de Empresa e Iniciativa Emprendedora, el APE (Aula Profesional de Emprendimiento) en colaboraci\u00f3n con el Departamento de Formaci\u00f3n y Orientaci\u00f3n Laboral, organiza la primera edici\u00f3n del concurso \u201cLA IDEA M\u00c1S BRILLANTE DEL IES ROSA CHACEL\u201d. EnLeer&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/posts\/1948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=1948"}],"version-history":[{"count":4,"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/posts\/1948\/revisions"}],"predecessor-version":[{"id":1952,"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/posts\/1948\/revisions\/1952"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=1948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/categories?post=1948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=1948"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.rosachacel.madrid\/index.php\/wp-json\/wp\/v2\/post_folder?post=1948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}