{"id":9115,"date":"2025-06-13T11:39:22","date_gmt":"2025-06-13T09:39:22","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/?p=9115"},"modified":"2025-06-23T11:57:53","modified_gmt":"2025-06-23T09:57:53","slug":"proyecto-de-emprendimiento-presupuesto-personal-y-consumo-responsable","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/2025\/06\/13\/proyecto-de-emprendimiento-presupuesto-personal-y-consumo-responsable\/","title":{"rendered":"Proyecto de Emprendimiento, presupuesto personal y consumo responsable"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Los alumnos y alumnas de 3\u00ba de la ESO dentro del <strong>proyecto de \u201cEmprendimiento, presupuesto personal y consumo responsable\u201d<\/strong> han realizado un trabajo fin de curso en el que han profundizado en la problem\u00e1tica de la industria textil y la huella que deja en nuestro planeta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A trav\u00e9s de diferentes actividades de sensibilizaci\u00f3n, los alumnos han investigado sobre el impacto que tiene en el mundo la ropa que compran y como un simple gesto puede minimizar el da\u00f1o que esta industria hace en los pa\u00edses productores.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Partiendo de una prenda de ropa propia han realizado la trazabilidad desde la materia prima hasta que la prenda est\u00e1 confeccionada y puede comprarse en Espa\u00f1a. Han podido analizar los diferentes pa\u00edses por los que pasa la producci\u00f3n y qu\u00e9 impacto tienen en el proceso en cada uno de estos pa\u00edses. Han podido comprobar que los pa\u00edses productores sufren en gran medida la contaminaci\u00f3n de la industria y que papel tienen cada uno de los agentes implicados (consumidores, productores y Estado) para solucionar este gran problema.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Despu\u00e9s, han investigado la brecha que se produce entre los pa\u00edses que disfrutan de la producci\u00f3n textil, como es el caso de Espa\u00f1a, y aquellos que reciben los residuos de nuestras prendas de ropa. Han podido evaluar el impacto medioambiental y humano, y la desigualdad social que genera. Ya que para terminar, han analizado diferente indicadores econ\u00f3micos, tales como, la salario m\u00ednimo, la jornada laboral o la edad m\u00ednima para trabajar, con el fin de ver la diferencia entre un pa\u00eds que disfruta de la producci\u00f3n, otro que sufre el impacto del proceso productivo, y un tercer pa\u00eds que sufre el impacto por la recepci\u00f3n de los residuos generados del consumo irresponsable.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aqu\u00ed os dejamos un trabajo realizado por uno de los grupos. Han utilizando la tecnolog\u00eda Scratch para crear la trazabilidad comentada mostrando los datos econ\u00f3micos, lo que nos permite observar la brecha social que se produce entre los pa\u00edses que disfrutan de la producci\u00f3n y los que sufren los efectos de su industria.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin duda, un trabajo que ha conmovido a nuestro alumnado y que confiamos nos permita aportar un granito de arena para minimizar el impacto de esta industria en nuestro querido planeta.\u00a0<\/span><\/p>\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-mediateca-bloque-mediateca aligncenter align wide\"><iframe loading=\"lazy\" src=\"https:\/\/mediateca.educa.madrid.org\/video\/9ztasqnoob96z4gt\/fs\" width=\"420\" height=\"315\" frameborder=\"0\" scrolling=\"no\" style=\"border:0;overflow:hidden\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos y alumnas de 3\u00ba de la ESO dentro del proyecto de \u201cEmprendimiento, presupuesto personal y consumo responsable\u201d han realizado un trabajo fin de curso en el que han profundizado en la problem\u00e1tica de la industria textil y la huella que deja en nuestro planeta. A trav\u00e9s de diferentes actividades de sensibilizaci\u00f3n, los alumnos<\/p><\/div>\n<div class=\"blog-btn\"><a href=\"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/2025\/06\/13\/proyecto-de-emprendimiento-presupuesto-personal-y-consumo-responsable\/\" class=\"home-blog-btn\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":3,"featured_media":9127,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"post_folder":[],"class_list":["post-9115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-e1750672667327.jpg",300,188,false],"landscape":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-e1750672667327.jpg",300,188,false],"portraits":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-e1750672667327.jpg",300,188,false],"thumbnail":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-300x188.jpg",300,188,true],"large":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-1024x640.jpg",696,435,true],"thumblist":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-500x500.jpg",500,500,true],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-1536x960.jpg",1536,960,true],"2048x2048":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-e1750672667327.jpg",300,188,false],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-272x182.jpg",272,182,true],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-e1750672667327.jpg",300,188,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-e1750672667327.jpg",300,188,false],"sow-blog-portfolio":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-375x375.jpg",375,375,true],"sow-blog-grid":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-720x480.jpg",720,480,true],"sow-blog-alternate":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-950x630.jpg",950,630,true],"rt_custom":["https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/\/wp-content\/uploads\/ies.satafi.getafe\/2025\/06\/proyecto-Emprendimiento-e1750672667327.jpg",300,188,false]},"rttpg_author":{"display_name":"ies.satafi.getafe","author_link":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/author\/cuenta_ies-satafi-getafe\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/category\/novedades\/\" rel=\"category tag\">Novedades<\/a>","rttpg_excerpt":"Los alumnos y alumnas de 3\u00ba de la ESO dentro del proyecto de \u201cEmprendimiento, presupuesto personal y consumo responsable\u201d han realizado un trabajo fin de curso en el que han profundizado en la problem\u00e1tica de la industria textil y la huella que deja en nuestro planeta. A trav\u00e9s de diferentes actividades de sensibilizaci\u00f3n, los alumnosLeer&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/wp-json\/wp\/v2\/posts\/9115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/wp-json\/wp\/v2\/comments?post=9115"}],"version-history":[{"count":7,"href":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/wp-json\/wp\/v2\/posts\/9115\/revisions"}],"predecessor-version":[{"id":9126,"href":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/wp-json\/wp\/v2\/posts\/9115\/revisions\/9126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/wp-json\/wp\/v2\/media\/9127"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/wp-json\/wp\/v2\/media?parent=9115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/wp-json\/wp\/v2\/categories?post=9115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/wp-json\/wp\/v2\/tags?post=9115"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.satafi.getafe\/index.php\/wp-json\/wp\/v2\/post_folder?post=9115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}