{"id":421,"date":"2021-04-23T21:54:07","date_gmt":"2021-04-23T21:54:07","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/?p=421"},"modified":"2025-11-18T09:55:10","modified_gmt":"2025-11-18T08:55:10","slug":"plan-de-estudios","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/2021\/04\/23\/plan-de-estudios\/","title":{"rendered":"Plan de estudios"},"content":{"rendered":"\n<p class=\"has-pale-cyan-blue-background-color has-background has-medium-font-size\"><strong>Los m\u00f3dulos de este ciclo formativo son los siguientes:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ciencias aplicadas I.\n<ul class=\"wp-block-list\">\n<li>Matem\u00e1ticas y Ciencias Aplicadas I.<\/li>\n\n\n\n<li>Ciencias de la Actividad F\u00edsica I.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Comunicaci\u00f3n y sociedad I.\n<ul class=\"wp-block-list\">\n<li>Comunicaci\u00f3n en Lengua Castellana y Sociedad I.<\/li>\n\n\n\n<li>Comunicaci\u00f3n en Lengua Inglesa I.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Itinerario personal para la empleabilidad.<\/li>\n\n\n\n<li>Operaciones b\u00e1sicas de fabricaci\u00f3n.<\/li>\n\n\n\n<li>Soldadura y carpinter\u00eda met\u00e1lica.<\/li>\n\n\n\n<li>Carpinter\u00eda de aluminio y PVC.<\/li>\n\n\n\n<li>Ciencias aplicadas II.\n<ul class=\"wp-block-list\">\n<li>Matem\u00e1ticas y Ciencias Aplicadas II<\/li>\n\n\n\n<li>Ciencias de la Actividad F\u00edsica II.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Comunicaci\u00f3n y sociedad II.\n<ul class=\"wp-block-list\">\n<li>Comunicaci\u00f3n en Lengua Castellana y Sociedad II.<\/li>\n\n\n\n<li>Comunicaci\u00f3n en Lengua Inglesa II.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Redes de evacuaci\u00f3n.<\/li>\n\n\n\n<li>Fontaner\u00eda y calefacci\u00f3n b\u00e1sica.<\/li>\n\n\n\n<li>Montaje de equipos de climatizaci\u00f3n<\/li>\n\n\n\n<li>Proyecto intermodular de aprendizaje colaborativo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Los m\u00f3dulos de este ciclo formativo son los siguientes:<\/p>\n","protected":false},"author":2,"featured_media":868,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"post_folder":[],"class_list":["post-421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabricacion-y-montaje"],"rttpg_featured_image_url":{"full":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-scaled.jpg",2560,1729,false],"landscape":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-scaled.jpg",2560,1729,false],"portraits":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-scaled.jpg",2560,1729,false],"thumbnail":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-150x150.jpg",150,150,true],"medium":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-300x203.jpg",300,203,true],"large":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-1024x691.jpg",696,470,true],"thumblist":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-scaled.jpg",500,338,false],"meccarouselthumb":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-474x324.jpg",474,324,true],"gridsquare":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-391x260.jpg",391,260,true],"tileview":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-300x400.jpg",300,400,true],"1536x1536":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-1536x1037.jpg",1536,1037,true],"2048x2048":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-2048x1383.jpg",2048,1383,true],"sow-carousel-default":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-scaled.jpg",269,182,false],"sow-post-carousel-overlay-theme":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-scaled.jpg",360,243,false],"sow-post-carousel-cards-theme":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-scaled.jpg",355,240,false],"rt_custom":["https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/\/wp-content\/uploads\/ies.victoria.villarejo\/2021\/04\/industrial-worker-at-the-factory-welding-steel-structure-scaled.jpg",2560,1729,false]},"rttpg_author":{"display_name":"tic.ies.victoria.villarejo","author_link":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/author\/cuenta_tic-ies-victoria-villarejo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/category\/fabricacion-y-montaje\/\" rel=\"category tag\">Fabricaci\u00f3n y Montaje<\/a>","rttpg_excerpt":"Los m\u00f3dulos de este ciclo formativo son los siguientes:","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/wp-json\/wp\/v2\/posts\/421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/wp-json\/wp\/v2\/comments?post=421"}],"version-history":[{"count":4,"href":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/wp-json\/wp\/v2\/posts\/421\/revisions"}],"predecessor-version":[{"id":5653,"href":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/wp-json\/wp\/v2\/posts\/421\/revisions\/5653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/wp-json\/wp\/v2\/media\/868"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/wp-json\/wp\/v2\/media?parent=421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/wp-json\/wp\/v2\/categories?post=421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/wp-json\/wp\/v2\/tags?post=421"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.victoria.villarejo\/index.php\/wp-json\/wp\/v2\/post_folder?post=421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}