{"id":10561,"date":"2026-02-20T13:17:59","date_gmt":"2026-02-20T12:17:59","guid":{"rendered":"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/?p=10561"},"modified":"2026-03-13T13:28:29","modified_gmt":"2026-03-13T12:28:29","slug":"boletines-de-la-2a-evaluacion","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/2026\/02\/20\/boletines-de-la-2a-evaluacion\/","title":{"rendered":"Boletines de la 2\u00aa evaluaci\u00f3n: ESO, Diversificaci\u00f3n, Bachillerato y Formaci\u00f3n Profesional."},"content":{"rendered":"<p>Los boletines correspondientes a la <strong>2\u00aa evaluaci\u00f3n<\/strong> se enviar\u00e1n a trav\u00e9s del correo EducaMadrid del alumnado. Tambi\u00e9n se podr\u00e1 visualizar a trav\u00e9s de la aplicaci\u00f3n Robles. Las fechas de recepci\u00f3n ser\u00e1n las siguientes:<\/p>\n<ul>\n<li><strong>1\u00ba de Bachillerato<\/strong>: jueves 26 de febrero.<\/li>\n<li><strong>2\u00ba de Bachillerato<\/strong>: viernes 20 de febrero.<\/li>\n<li><strong>1\u00ba de Formaci\u00f3n Profesional de grado medio y grado superior<\/strong>: lunes 23 de febrero.<\/li>\n<li><strong>ESO y Diversificaci\u00f3n<\/strong>: lunes 16 de marzo.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Los boletines correspondientes a la 2\u00aa evaluaci\u00f3n se enviar\u00e1n a trav\u00e9s del correo EducaMadrid del alumnado. Tambi\u00e9n se podr\u00e1 visualizar a trav\u00e9s de la aplicaci\u00f3n Robles. Las fechas de recepci\u00f3n &#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"post_folder":[],"class_list":["post-10561","post","type-post","status-publish","format-standard","hentry","category-destacadas","category-noticias"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"ies.villablanca.madrid","author_link":"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/author\/cuenta_ies-villablanca-madrid\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/category\/noticias\/destacadas\/\" rel=\"category tag\">Destacadas<\/a> <a href=\"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Los boletines correspondientes a la 2\u00aa evaluaci\u00f3n se enviar\u00e1n a trav\u00e9s del correo EducaMadrid del alumnado. Tambi\u00e9n se podr\u00e1 visualizar a trav\u00e9s de la aplicaci\u00f3n Robles. Las fechas de recepci\u00f3n ...","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/wp-json\/wp\/v2\/posts\/10561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/wp-json\/wp\/v2\/comments?post=10561"}],"version-history":[{"count":6,"href":"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/wp-json\/wp\/v2\/posts\/10561\/revisions"}],"predecessor-version":[{"id":10709,"href":"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/wp-json\/wp\/v2\/posts\/10561\/revisions\/10709"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/wp-json\/wp\/v2\/media?parent=10561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/wp-json\/wp\/v2\/categories?post=10561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/wp-json\/wp\/v2\/tags?post=10561"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/ies.villablanca.madrid\/index.php\/wp-json\/wp\/v2\/post_folder?post=10561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}