{"id":2925,"date":"2023-01-10T11:50:31","date_gmt":"2023-01-10T11:50:31","guid":{"rendered":"https:\/\/raices.educa.madrid.org\/?p=2925"},"modified":"2023-01-10T11:50:31","modified_gmt":"2023-01-10T11:50:31","slug":"generacion-modelo-233-aeat-en-ceip-con-primer-ciclo-de-educacion-infantil","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/raices\/generacion-modelo-233-aeat-en-ceip-con-primer-ciclo-de-educacion-infantil\/","title":{"rendered":"Generaci\u00f3n modelo 233 AEAT en CEIP con Primer Ciclo de Educaci\u00f3n Infantil"},"content":{"rendered":"<p>En esta breve gu\u00eda, se explica c\u00f3mo obtener en Ra\u00edces el Archivo con la informaci\u00f3n requerida por la Agencia Tributaria a las Escuelas Infantiles de Primer Ciclo de Educaci\u00f3n Infantil, y m\u00e1s concretamente a los CEIP con Primer Ciclo de Educaci\u00f3n Infantil.<\/p>\n<p><a href=\"https:\/\/site.educa.madrid.org\/raices\/\/wp-content\/uploads\/raices\/2023\/01\/Guia-Visual-Modelo-233-CEIP-con-primer-ciclo.pdf\">Gu\u00eda Visual Modelo 233 CEIP con primer ciclo<\/a><\/p>\n<p>M\u00e1s informaci\u00f3n: <a href=\"https:\/\/sede.agenciatributaria.gob.es\/Sede\/procedimientoini\/GI45.shtml\">Presentaci\u00f3n electr\u00f3nica del modelo 233 \u2013 Agencia Tributaria<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta breve gu\u00eda, se explica c\u00f3mo obtener en Ra\u00edces el Archivo con la informaci\u00f3n requerida por la Agencia Tributaria a las Escuelas Infantiles de Primer Ciclo de Educaci\u00f3n Infantil, y m\u00e1s concretamente a los CEIP con Primer Ciclo de Educaci\u00f3n Infantil. Gu\u00eda Visual Modelo 233 CEIP con primer ciclo M\u00e1s informaci\u00f3n: Presentaci\u00f3n electr\u00f3nica del [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42,14],"tags":[88,188,273],"post_folder":[],"class_list":["post-2925","post","type-post","status-publish","format-standard","hentry","category-guia","category-infantil-0-3","tag-aeat","tag-eeii","tag-modelo-233"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Vicente Mart\u00ednez Garc\u00eda","author_link":"https:\/\/site.educa.madrid.org\/raices\/author\/vicente_martinez-garcia\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/raices\/category\/publicacion\/guia\/\" rel=\"category tag\">Gu\u00eda<\/a> <a href=\"https:\/\/site.educa.madrid.org\/raices\/category\/etapa-educativa\/infantil-0-3\/\" rel=\"category tag\">Infantil 0-3<\/a>","rttpg_excerpt":"En esta breve gu\u00eda, se explica c\u00f3mo obtener en Ra\u00edces el Archivo con la informaci\u00f3n requerida por la Agencia Tributaria a las Escuelas Infantiles de Primer Ciclo de Educaci\u00f3n Infantil, y m\u00e1s concretamente a los CEIP con Primer Ciclo de Educaci\u00f3n Infantil. Gu\u00eda Visual Modelo 233 CEIP con primer ciclo M\u00e1s informaci\u00f3n: Presentaci\u00f3n electr\u00f3nica del&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/posts\/2925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/comments?post=2925"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/posts\/2925\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/media?parent=2925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/categories?post=2925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/tags?post=2925"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/post_folder?post=2925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}