{"id":3206,"date":"2023-04-19T21:23:40","date_gmt":"2023-04-19T21:23:40","guid":{"rendered":"https:\/\/raices.educa.madrid.org\/?p=3206"},"modified":"2023-04-19T21:23:40","modified_gmt":"2023-04-19T21:23:40","slug":"nuevas-mejoras-en-el-modulo-de-inspeccion-abril-2023","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/raices\/nuevas-mejoras-en-el-modulo-de-inspeccion-abril-2023\/","title":{"rendered":"Nuevas mejoras en el m\u00f3dulo de Inspecci\u00f3n (abril 2023)"},"content":{"rendered":"\n<p class=\"has-medium-font-size\">Se publica gu\u00eda con las nuevas mejoras introducidas en el m\u00f3dulo de Inspecci\u00f3n:<\/p>\n\n\n\n<ol type=\"1\" class=\"has-small-font-size wp-block-list\"><li>Acceso al DOC para el perfil de AT inspecci\u00f3n<\/li><li>Explotaci\u00f3n de datos con Plan General de Inspecci\u00f3n Educativa para perfil AT Inspecci\u00f3n<\/li><li>Archivado de documentos para Inspectores sin distrito asociados a DAT<\/li><li>Consulta de Profesionales adscritos a un centro para el perfil de Inspecci\u00f3n<\/li><li>Pantalla multiregistro con campo <em>asunto<\/em> e <em>inspector<\/em> en Documentos de Entrada<\/li><li>Opci\u00f3n de Copia de documentos de entrada para el perfil AT Inspecci\u00f3n<\/li><li>Asociar un n\u00famero de Ereg a inspectores de varios distritos<\/li><li>Funci\u00f3n de texto predictivo a \u201c\u00e1mbitos\u201d<\/li><\/ol>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/site.educa.madrid.org\/raices\/\/wp-content\/uploads\/raices\/2023\/04\/GUIA-MEJORAS-FASE-III.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"489\" height=\"430\" src=\"https:\/\/site.educa.madrid.org\/raices\/\/wp-content\/uploads\/raices\/2023\/04\/imagen-guias-mejoras.png\" alt=\"\" class=\"wp-image-3204\" srcset=\"https:\/\/site.educa.madrid.org\/raices\/\/wp-content\/uploads\/raices\/2023\/04\/imagen-guias-mejoras.png 489w, https:\/\/site.educa.madrid.org\/raices\/\/wp-content\/uploads\/raices\/2023\/04\/imagen-guias-mejoras-300x264.png 300w\" sizes=\"auto, (max-width: 489px) 100vw, 489px\" \/><\/a><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se publica gu\u00eda con las nuevas mejoras introducidas en el m\u00f3dulo de Inspecci\u00f3n: Acceso al DOC para el perfil de AT inspecci\u00f3n Explotaci\u00f3n de datos con Plan General de Inspecci\u00f3n Educativa para perfil AT Inspecci\u00f3n Archivado de documentos para Inspectores sin distrito asociados a DAT Consulta de Profesionales adscritos a un centro para el perfil [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,1],"tags":[66,252],"post_folder":[],"class_list":["post-3206","post","type-post","status-publish","format-standard","hentry","category-sie","category-sin-categoria","tag-inspeccion-educativa","tag-inspeccion"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Laura Mar\u00edn Ram\u00edrez","author_link":"https:\/\/site.educa.madrid.org\/raices\/author\/laura_marn-ramrez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/raices\/category\/destinatarios\/sie\/\" rel=\"category tag\">SIE<\/a> <a href=\"https:\/\/site.educa.madrid.org\/raices\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a>","rttpg_excerpt":"Se publica gu\u00eda con las nuevas mejoras introducidas en el m\u00f3dulo de Inspecci\u00f3n: Acceso al DOC para el perfil de AT inspecci\u00f3n Explotaci\u00f3n de datos con Plan General de Inspecci\u00f3n Educativa para perfil AT Inspecci\u00f3n Archivado de documentos para Inspectores sin distrito asociados a DAT Consulta de Profesionales adscritos a un centro para el perfil&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/posts\/3206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/comments?post=3206"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/posts\/3206\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/media?parent=3206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/categories?post=3206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/tags?post=3206"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/post_folder?post=3206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}