{"id":5286,"date":"2020-10-06T15:38:16","date_gmt":"2020-10-06T15:38:16","guid":{"rendered":"https:\/\/raices.educa.madrid.org\/?p=440"},"modified":"2020-10-06T15:38:16","modified_gmt":"2020-10-06T15:38:16","slug":"desbloqueo-de-usuarios-en-raices-y-roble","status":"publish","type":"post","link":"https:\/\/site.educa.madrid.org\/raices\/desbloqueo-de-usuarios-en-raices-y-roble\/","title":{"rendered":"Desbloqueo de usuarios en Ra\u00edces y Roble"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignright size-medium\"><a href=\"\/wp-content\/uploads\/2020\/10\/Desbloqueo-de-usuarios-en-Ra\u00edces-o-Roble.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" src=\"https:\/\/site.educa.madrid.org\/raices\/\/wp-content\/uploads\/raices\/2020\/10\/Desbloqueo-de-usuarios-en-Raices-o-Roble-v7-258x300.png\" alt=\"\" class=\"wp-image-442\"\/><\/a><\/figure><\/div>\n\n\n\n<p>En este diagrama descargable (PDF) se indica c\u00f3mo se puede proceder para desbloquear un usuario. Este usuario es el mismo tanto en Ra\u00edces como en Roble.<\/p>\n\n\n\n<p>El caso m\u00e1s sencillo y habitual consiste en que el propio interesado pueda desbloquear su usuario mediante una recuperaci\u00f3n de contrase\u00f1a. \u00danicamente hacen falta dos requisitos para ello:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Recordar la respuesta a la pregunta de seguridad.<\/li><li>Tener informado un correo electr\u00f3nico para recibir por este medio la nueva contrase\u00f1a.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/site.educa.madrid.org\/raices\/\/wp-content\/uploads\/raices\/2020\/10\/Desbloqueo-de-usuarios-en-Raices-o-Roble.pdf\">Desbloqueo de usuarios en Ra\u00edces o Roble<\/a><a href=\"https:\/\/site.educa.madrid.org\/raices\/\/wp-content\/uploads\/raices\/2020\/10\/Desbloqueo-de-usuarios-en-Raices-o-Roble.pdf\" class=\"wp-block-file__button\" download>Descarga<\/a><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este diagrama descargable (PDF) se indica c\u00f3mo se puede proceder para desbloquear un usuario. Este usuario es el mismo tanto en Ra\u00edces como en Roble. El caso m\u00e1s sencillo y habitual consiste en que el propio interesado pueda desbloquear su usuario mediante una recuperaci\u00f3n de contrase\u00f1a. \u00danicamente hacen falta dos requisitos para ello: Recordar [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,29,31,34,22],"tags":[148,166,354],"post_folder":[],"class_list":["post-5286","post","type-post","status-publish","format-standard","hentry","category-centro-educativo","category-centros-concertados","category-comunicaciones","category-dat","category-tutores-legales","tag-contrasena","tag-desbloqueo","tag-usuario"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Victor Eugenio Nu\u00f1o Nu\u00f1o","author_link":"https:\/\/site.educa.madrid.org\/raices\/author\/victoreugenio-nunonuno\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/site.educa.madrid.org\/raices\/category\/destinatarios\/centro-educativo\/\" rel=\"category tag\">Centro educativo<\/a> <a href=\"https:\/\/site.educa.madrid.org\/raices\/category\/destinatarios\/centros-concertados\/\" rel=\"category tag\">Centros concertados<\/a> <a href=\"https:\/\/site.educa.madrid.org\/raices\/category\/procedimientos\/comunicaciones\/\" rel=\"category tag\">Comunicaciones<\/a> <a href=\"https:\/\/site.educa.madrid.org\/raices\/category\/destinatarios\/dat\/\" rel=\"category tag\">DAT<\/a> <a href=\"https:\/\/site.educa.madrid.org\/raices\/category\/destinatarios\/tutores-legales\/\" rel=\"category tag\">Tutores legales<\/a>","rttpg_excerpt":"En este diagrama descargable (PDF) se indica c\u00f3mo se puede proceder para desbloquear un usuario. Este usuario es el mismo tanto en Ra\u00edces como en Roble. El caso m\u00e1s sencillo y habitual consiste en que el propio interesado pueda desbloquear su usuario mediante una recuperaci\u00f3n de contrase\u00f1a. \u00danicamente hacen falta dos requisitos para ello: Recordar&hellip;","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/posts\/5286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/comments?post=5286"}],"version-history":[{"count":0,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/posts\/5286\/revisions"}],"wp:attachment":[{"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/media?parent=5286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/categories?post=5286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/tags?post=5286"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/site.educa.madrid.org\/raices\/wp-json\/wp\/v2\/post_folder?post=5286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}